{"id":2766,"date":"2000-03-20T00:14:18","date_gmt":"2000-03-19T22:14:18","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2766"},"modified":"2017-11-09T10:39:18","modified_gmt":"2017-11-09T08:39:18","slug":"03-20-14","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/","title":{"rendered":"14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale"},"content":{"rendered":"<p>Les Cohanim sont tenus de b\u00e9nir l\u2019assembl\u00e9e\u00a0; toutefois la b\u00e9n\u00e9diction vient de Dieu seul, et ne d\u00e9pend pas de la pi\u00e9t\u00e9 des Cohanim. Par cons\u00e9quent, m\u00eame un Cohen qui fauterait en mangeant des aliments interdits, en ayant des relations charnelles interdites, ou en commettant quelque autre faute, n\u2019en serait pas moins tenu de monter sur l\u2019estrade. Et s\u2019il s\u2019abstenait de prendre part \u00e0 la b\u00e9n\u00e9diction, il ne ferait qu\u2019ajouter une faute suppl\u00e9mentaire au nombre de ses p\u00e9ch\u00e9s. Comme l\u2019\u00e9crit Ma\u00efmonide\u00a0(<em>Hilkhot T\u00e9phila<\/em> 15, 6)\u00a0: \u00ab\u00a0On ne dit pas \u00e0 un homme impie\u00a0: \u201cAjoute encore une impi\u00e9t\u00e9 en t\u2019abstenant d\u2019accomplir les mitsvot.\u201d\u00a0\u00bb<\/p>\n<p>En revanche, si un Cohen a commis des fautes entachant sa pr\u00eatrise, par exemple s\u2019il a \u00e9pous\u00e9 une femme divorc\u00e9e, ou s\u2019il s\u2019est rendu impur au contact de morts, nos sages le sanctionnent en lui interdisant de proc\u00e9der \u00e0 la b\u00e9n\u00e9diction. De m\u00eame un Cohen qui a pris part \u00e0 un culte idol\u00e2tre, ou qui transgresse le Chabbat publiquement dans le but de provoquer les autres, est disqualifi\u00e9 pour la b\u00e9n\u00e9diction sacerdotale. Mais si un Cohen qui aurait commis l\u2019une de ces fautes se repent d\u2019un entier repentir, il pourra de nouveau prendre part \u00e0 la b\u00e9n\u00e9diction (<em>Choul\u2019han \u2018Aroukh<\/em>, <em>Ora\u2019h \u2018Ha\u00efm<\/em> 128, paragraphes 37, 40, 41\u00a0; <em>La Pri\u00e8re d\u2019Isra\u00ebl<\/em> 20 \u00a7 10).<\/p>\n<p>Un Cohen qui a tu\u00e9 une personne ne peut prendre part \u00e0 la <em>Birkat Cohanim<\/em>, comme il est dit\u00a0(Is 1, 15) : \u00ab\u00a0Lorsque vous \u00e9tendez les mains, je d\u00e9tourne les yeux de vous\u2026 vos mains sont pleines de sang\u00a0\u00bb (<em>Berakhot<\/em> 32b). Le r\u00f4le du Cohen est d\u2019ajouter \u00e0 la bont\u00e9 et \u00e0 la vie, comme le faisait Aaron le grand-pr\u00eatre, qui aimait la paix et poursuivait la paix\u00a0; tandis qu\u2019un Cohen qui a tu\u00e9 a port\u00e9 atteinte au fondement de sa pr\u00eatrise. De m\u00eame, si un Cohen a, de fa\u00e7on involontaire, \u00e9cras\u00e9 mortellement une personne en voiture, il est disqualifi\u00e9 \u00e0 l\u2019\u00e9gard de la <em>Birkat Cohanim<\/em>. Les d\u00e9cisionnaires sont partag\u00e9s sur la question de savoir si, apr\u00e8s s\u2019\u00eatre repenti \u00e0 l\u2019aide de je\u00fbnes, de dons et de r\u00e9solutions pour l\u2019avenir, un tel Cohen pourrait prendre de nouveau part \u00e0 la b\u00e9n\u00e9diction. En pratique, un Cohen qui aurait \u00e9t\u00e9 l\u2019acteur d\u2019un \u00e9v\u00e9nement aussi grave doit aller consulter son rabbin afin de recueillir ses directives personnelles sur la conduite \u00e0 tenir (cf. <em>La Pri\u00e8re d\u2019Isra\u00ebl<\/em> 20, 11).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Cohanim sont tenus de b\u00e9nir l\u2019assembl\u00e9e\u00a0; toutefois la b\u00e9n\u00e9diction vient de Dieu seul, et ne d\u00e9pend pas de la pi\u00e9t\u00e9 des Cohanim. Par cons\u00e9quent, m\u00eame un Cohen qui fauterait en mangeant des aliments interdits, en ayant des relations charnelles interdites, ou en commettant quelque autre faute, n\u2019en serait pas moins tenu de monter sur [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2766","post","type-post","status-publish","format-standard","hentry","category-03-20"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Les Cohanim sont tenus de b\u00e9nir l\u2019assembl\u00e9e\u00a0; toutefois la b\u00e9n\u00e9diction vient de Dieu seul, et ne d\u00e9pend pas de la pi\u00e9t\u00e9 des Cohanim. Par cons\u00e9quent, m\u00eame un Cohen qui fauterait en mangeant des aliments interdits, en ayant des relations charnelles interdites, ou en commettant quelque autre faute, n\u2019en serait pas moins tenu de monter sur [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-19T22:14:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T08:39:18+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-14\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-14\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale\",\"datePublished\":\"2000-03-19T22:14:18+00:00\",\"dateModified\":\"2017-11-09T08:39:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-14\\\/\"},\"wordCount\":443,\"articleSection\":[\"Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-14\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-14\\\/\",\"name\":\"14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-19T22:14:18+00:00\",\"dateModified\":\"2017-11-09T08:39:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-14\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-14\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/","og_locale":"fr_FR","og_type":"article","og_title":"14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale - Pnin\u00e9 Halakha","og_description":"Les Cohanim sont tenus de b\u00e9nir l\u2019assembl\u00e9e\u00a0; toutefois la b\u00e9n\u00e9diction vient de Dieu seul, et ne d\u00e9pend pas de la pi\u00e9t\u00e9 des Cohanim. Par cons\u00e9quent, m\u00eame un Cohen qui fauterait en mangeant des aliments interdits, en ayant des relations charnelles interdites, ou en commettant quelque autre faute, n\u2019en serait pas moins tenu de monter sur [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-19T22:14:18+00:00","article_modified_time":"2017-11-09T08:39:18+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale","datePublished":"2000-03-19T22:14:18+00:00","dateModified":"2017-11-09T08:39:18+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/"},"wordCount":443,"articleSection":["Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/","name":"14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-19T22:14:18+00:00","dateModified":"2017-11-09T08:39:18+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-20-14\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"14. Aptitudes et inaptitudes \u00e0 la b\u00e9n\u00e9diction sacerdotale"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2766"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2766\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}