{"id":2770,"date":"2000-03-20T00:16:40","date_gmt":"2000-03-19T22:16:40","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2770"},"modified":"2017-11-09T10:41:09","modified_gmt":"2017-11-09T08:41:09","slug":"03-20-16","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/","title":{"rendered":"16. L\u2019officiant"},"content":{"rendered":"<p>L\u2019officiant (<em>\u2018hazan<\/em>) conduit la pri\u00e8re. \u00c0 certains moments, toute l\u2019assembl\u00e9e r\u00e9cite avec lui la pri\u00e8re, tandis que lui fixe le rythme\u00a0; \u00e0 d\u2019autres moments, il est seul \u00e0 prononcer la pri\u00e8re, les fid\u00e8les r\u00e9pondant <em>amen<\/em>, comme dans la r\u00e9p\u00e9tition de la \u2018Amida ou les diff\u00e9rentes mentions du Qaddich. Aussi l\u2019officiant doit-il \u00eatre convenable, de bon renom, modeste, agr\u00e9\u00e9 par ses pairs, poss\u00e9der une voix agr\u00e9able et \u00eatre habitu\u00e9 \u00e0 lire la Torah \u00e9crite\u00a0: Pentateuque, Proph\u00e8tes et Hagiographes (<em>Ta\u2019anit<\/em> 16b\u00a0; <em>Choul\u2019han \u2018Aroukh <\/em>53, 4). Il faut particuli\u00e8rement insister sur lesdites conditions durant les jours redoutables (de Roch Hachana \u00e0 Yom Kippour) et les jours de je\u00fbne, car alors nous prions et implorons le Saint b\u00e9ni soit-Il de nous pardonner nos fautes, de nous \u00e9pargner toute souffrance et de h\u00e2ter notre D\u00e9livrance\u00a0; or si l\u2019officiant p\u00e2tit d\u2019un d\u00e9faut, la pri\u00e8re de l\u2019assembl\u00e9e risque de ne pas s\u2019\u00e9lever convenablement vers Dieu (Rama, <em>Ora\u2019h \u2018Ha\u00efm<\/em> 581, 1).<\/p>\n<p>\u00c0 l\u2019\u00e9poque talmudique, il \u00e9tait interdit d\u2019\u00e9crire des recueils de pri\u00e8re, car seule la Torah \u00e9crite, c\u2019est-\u00e0-dire la Bible, \u00e9tait autoris\u00e9e \u00e0 la copie, tandis qu\u2019il \u00e9tait interdit de porter \u00e0 l\u2019\u00e9crit la tradition orale, au sein de laquelle on trouve les pri\u00e8res et les b\u00e9n\u00e9dictions institu\u00e9es par les sages (<em>Temoura<\/em> 14b). D\u00e8s lors, le r\u00f4le de l\u2019officiant \u00e9tait tr\u00e8s important, car il devait conna\u00eetre toute la pri\u00e8re par c\u0153ur et la r\u00e9citer \u00e0 voix haute, afin d\u2019acquitter les fid\u00e8les de leur obligation. On choisissait alors un officiant permanent pour remplir cette haute fonction\u00a0; et toutes les conditions \u00e9nonc\u00e9es par les sages pour le choix d\u2019un officiant les jours de je\u00fbne \u00e9taient valables pour le choix d\u2019un officiant permanent. A priori, il fallait nommer un officiant qui conv\u00eent \u00e0 chaque membre de la communaut\u00e9, car celui-ci \u00e9tait destin\u00e9 \u00e0 acquitter chacun de son obligation.<\/p>\n<p>Cependant, apr\u00e8s la destruction du Deuxi\u00e8me Temple, nos sages ont consid\u00e9r\u00e9 que l\u2019on \u00e9tait contraint de permettre la mise \u00e0 l\u2019\u00e9crit des enseignements de la Torah orale afin qu\u2019elle ne f\u00fbt pas oubli\u00e9e par le peuple juif\u00a0; parmi lesdits enseignements, il devint permis de porter \u00e0 l\u2019\u00e9crit les pri\u00e8res. Au fil du temps, les livres de pri\u00e8re se r\u00e9pandirent, au point qu\u2019il ne fut plus n\u00e9cessaire que l\u2019officiant acquitt\u00e2t les fid\u00e8les de leur obligation, car tous priaient \u00e0 l\u2019aide de leur livre. D\u00e8s lors, il n\u2019est plus n\u00e9cessaire d\u2019\u00eatre aussi pointilleux dans le choix de l\u2019officiant, et l\u2019on ne d\u00e9signe plus d\u2019officiant permanent pour toute l\u2019ann\u00e9e\u00a0: chaque jour, une autre personne se tient au pupitre (<em>Choul\u2019han \u2018Aroukh<\/em> 53, 19\u00a0; <em>Michna Beroura<\/em> 53, 53).<\/p>\n<p>Malgr\u00e9 cela, les responsables de la communaut\u00e9 (<em>gaba\u00efm<\/em>) doivent faire en sorte que les officiants qui se pr\u00e9sentent au pupitre soient convenables, observent la Torah et les commandements, et que le public accepte qu\u2019ils soient leurs d\u00e9l\u00e9gu\u00e9s pour le temps de la pri\u00e8re, car les officiants ont la responsabilit\u00e9 de dire, par d\u00e9l\u00e9gation de l\u2019assembl\u00e9e, la r\u00e9p\u00e9tition de la \u2018Amida et le Qaddich (cf. <em>Kaf Ha\u2019ha\u00efm<\/em> 53, 86). Et pour ce qui concerne les offices de Chabbat et de f\u00eates, durant lesquels il est d\u2019usage que les officiants entonnent de v\u00e9ritables chants et cantiques pendant certains passages de la pri\u00e8re, on devra faire en sorte que les officiants poss\u00e8dent un talent musical et une belle voix.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019officiant (\u2018hazan) conduit la pri\u00e8re. \u00c0 certains moments, toute l\u2019assembl\u00e9e r\u00e9cite avec lui la pri\u00e8re, tandis que lui fixe le rythme\u00a0; \u00e0 d\u2019autres moments, il est seul \u00e0 prononcer la pri\u00e8re, les fid\u00e8les r\u00e9pondant amen, comme dans la r\u00e9p\u00e9tition de la \u2018Amida ou les diff\u00e9rentes mentions du Qaddich. Aussi l\u2019officiant doit-il \u00eatre convenable, de bon [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2770","post","type-post","status-publish","format-standard","hentry","category-03-20"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>16. L\u2019officiant - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"16. L\u2019officiant - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"L\u2019officiant (\u2018hazan) conduit la pri\u00e8re. \u00c0 certains moments, toute l\u2019assembl\u00e9e r\u00e9cite avec lui la pri\u00e8re, tandis que lui fixe le rythme\u00a0; \u00e0 d\u2019autres moments, il est seul \u00e0 prononcer la pri\u00e8re, les fid\u00e8les r\u00e9pondant amen, comme dans la r\u00e9p\u00e9tition de la \u2018Amida ou les diff\u00e9rentes mentions du Qaddich. Aussi l\u2019officiant doit-il \u00eatre convenable, de bon [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-19T22:16:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T08:41:09+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-16\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-16\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"16. L\u2019officiant\",\"datePublished\":\"2000-03-19T22:16:40+00:00\",\"dateModified\":\"2017-11-09T08:41:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-16\\\/\"},\"wordCount\":624,\"articleSection\":[\"Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-16\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-16\\\/\",\"name\":\"16. L\u2019officiant - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-19T22:16:40+00:00\",\"dateModified\":\"2017-11-09T08:41:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-16\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-16\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-16\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"16. L\u2019officiant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"16. L\u2019officiant - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/","og_locale":"fr_FR","og_type":"article","og_title":"16. L\u2019officiant - Pnin\u00e9 Halakha","og_description":"L\u2019officiant (\u2018hazan) conduit la pri\u00e8re. \u00c0 certains moments, toute l\u2019assembl\u00e9e r\u00e9cite avec lui la pri\u00e8re, tandis que lui fixe le rythme\u00a0; \u00e0 d\u2019autres moments, il est seul \u00e0 prononcer la pri\u00e8re, les fid\u00e8les r\u00e9pondant amen, comme dans la r\u00e9p\u00e9tition de la \u2018Amida ou les diff\u00e9rentes mentions du Qaddich. Aussi l\u2019officiant doit-il \u00eatre convenable, de bon [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-19T22:16:40+00:00","article_modified_time":"2017-11-09T08:41:09+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"16. L\u2019officiant","datePublished":"2000-03-19T22:16:40+00:00","dateModified":"2017-11-09T08:41:09+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/"},"wordCount":624,"articleSection":["Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/","name":"16. L\u2019officiant - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-19T22:16:40+00:00","dateModified":"2017-11-09T08:41:09+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-20-16\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-16\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"16. L\u2019officiant"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2770"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2770\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}