{"id":2775,"date":"2000-03-20T00:18:51","date_gmt":"2000-03-19T22:18:51","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2775"},"modified":"2017-11-09T10:49:37","modified_gmt":"2017-11-09T08:49:37","slug":"03-20-18","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/","title":{"rendered":"18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins"},"content":{"rendered":"<p>Quand on a perdu l\u2019un de ses deux parents, on doit r\u00e9citer le Qaddich \u00e0 l\u2019office, durant la premi\u00e8re ann\u00e9e. Il y a \u00e0 cela une grande utilit\u00e9 pour l\u2019\u00e2me du d\u00e9funt, celle de lui \u00e9pargner la rigueur du <em>Gu\u00e9hinom<\/em><sup><a href='#_te01ftn20_o' id='_te01ftnref20_o' class='aup1'>[o]<\/a><\/sup> car, d\u00e8s lors que le fils qu\u2019il laisse en ce monde sanctifie publiquement le nom divin, il appara\u00eet que sa vie \u00e9tait dot\u00e9e d\u2019une valeur \u00e9ternelle de saintet\u00e9. Si le fils du d\u00e9funt sait conduire l\u2019office et que l\u2019assembl\u00e9e y consente, il est bon qu\u2019il soit aussi officiant durant les jours ouvrables, car il y a dans le fait d\u2019\u00eatre officiant plus d\u2019utilit\u00e9 encore pour l\u2019\u00e2me du d\u00e9funt. Le jour du <em>jahrzeit<\/em> (anniversaire du d\u00e9c\u00e8s), chaque ann\u00e9e, les endeuill\u00e9s disent \u00e9galement le Qaddich et s\u2019efforcent d\u2019officier. Quand il y a plusieurs endeuill\u00e9s \u00e0 la synagogue, l\u2019usage est que tous r\u00e9citent le Qaddich ensemble. Quant \u00e0 officier, il existe un ordre de priorit\u00e9\u00a0: par exemple, l\u2019endeuill\u00e9 qui se trouve dans les trente jours apr\u00e8s le d\u00e9c\u00e8s de son parent a priorit\u00e9 sur celui qui se trouve dans l\u2019ann\u00e9e (cet ordre de priorit\u00e9 est expos\u00e9 plus en d\u00e9tail dans <em>La Pri\u00e8re d\u2019Isra\u00ebl <\/em>4, 5-7).<\/p>\n<p>Si un homme ou une femme d\u00e9c\u00e8de en ne laissant apr\u00e8s soi qu\u2019un fils mineur, ce fils dira le Qaddich en son souvenir, bien qu\u2019il ne soit pas arriv\u00e9 \u00e0 l\u2019\u00e2ge o\u00f9 l\u2019on est tenu d\u2019accomplir les commandements (<em>bar-mitsva<\/em>). C\u2019est d\u2019ailleurs \u00e0 cette fin qu\u2019a \u00e9t\u00e9 institu\u00e9 le Qaddich de l\u2019orphelin. En effet, pour un endeuill\u00e9 majeur, il est encore plus indiqu\u00e9 pour l\u2019\u00e9l\u00e9vation de l\u2019\u00e2me de ses parents\u00a0de conduire l\u2019office ; tandis que pour le mineur, qui ne peut \u00eatre officiant, on a institu\u00e9 ce Qaddich (Rama, <em>Yor\u00e9 D\u00e9\u2019a<\/em> 376, 4). M\u00eame si le mineur n\u2019est pas encore arriv\u00e9 \u00e0 l\u2019\u00e2ge de l\u2019\u00e9ducation aux <em>mitsvot<\/em> (autour de six ans), on lui lit le Qaddich \u00e0 haute voix, et lui, l\u2019endeuill\u00e9 mineur, r\u00e9p\u00e8te mot \u00e0 mot, tandis que l\u2019assembl\u00e9e r\u00e9pond <em>amen<\/em> \u00e0 sa suite.<\/p>\n<p>Il est bon qu\u2019un fils adopt\u00e9 r\u00e9cite le Qaddich pour ses parents adoptifs. \u00c0 plus forte raison s\u2019ils ne laissent pas d\u2019autre fils, ce sera une mitsva pour lui de dire le Qaddich pour ses parents adoptifs (<em>Yalqout Yossef<\/em> VII 23, 13). Il est bon qu\u2019un homme converti au juda\u00efsme r\u00e9cite le Qaddich pour ses parents non Juifs (r\u00e9f. cit. 14, <em>Pisq\u00e9 Techouva<\/em> 132, 20, <em>Zeqan Aharon, Yor\u00e9 D\u00e9\u2019a<\/em> 87).<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref20_o' id='_te01ftn20_o'>[o]<\/a>. S\u00e9jour des morts, et plus sp\u00e9cialement ici, lieu de l\u2019expiation des fautes.<\/li>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quand on a perdu l\u2019un de ses deux parents, on doit r\u00e9citer le Qaddich \u00e0 l\u2019office, durant la premi\u00e8re ann\u00e9e. Il y a \u00e0 cela une grande utilit\u00e9 pour l\u2019\u00e2me du d\u00e9funt, celle de lui \u00e9pargner la rigueur du Gu\u00e9hinom[o] car, d\u00e8s lors que le fils qu\u2019il laisse en ce monde sanctifie publiquement le nom [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2775","post","type-post","status-publish","format-standard","hentry","category-03-20"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Quand on a perdu l\u2019un de ses deux parents, on doit r\u00e9citer le Qaddich \u00e0 l\u2019office, durant la premi\u00e8re ann\u00e9e. Il y a \u00e0 cela une grande utilit\u00e9 pour l\u2019\u00e2me du d\u00e9funt, celle de lui \u00e9pargner la rigueur du Gu\u00e9hinom[o] car, d\u00e8s lors que le fils qu\u2019il laisse en ce monde sanctifie publiquement le nom [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-19T22:18:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T08:49:37+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-18\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-18\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins\",\"datePublished\":\"2000-03-19T22:18:51+00:00\",\"dateModified\":\"2017-11-09T08:49:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-18\\\/\"},\"wordCount\":482,\"articleSection\":[\"Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-18\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-18\\\/\",\"name\":\"18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-19T22:18:51+00:00\",\"dateModified\":\"2017-11-09T08:49:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-18\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-18\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-18\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/","og_locale":"fr_FR","og_type":"article","og_title":"18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins - Pnin\u00e9 Halakha","og_description":"Quand on a perdu l\u2019un de ses deux parents, on doit r\u00e9citer le Qaddich \u00e0 l\u2019office, durant la premi\u00e8re ann\u00e9e. Il y a \u00e0 cela une grande utilit\u00e9 pour l\u2019\u00e2me du d\u00e9funt, celle de lui \u00e9pargner la rigueur du Gu\u00e9hinom[o] car, d\u00e8s lors que le fils qu\u2019il laisse en ce monde sanctifie publiquement le nom [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-19T22:18:51+00:00","article_modified_time":"2017-11-09T08:49:37+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins","datePublished":"2000-03-19T22:18:51+00:00","dateModified":"2017-11-09T08:49:37+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/"},"wordCount":482,"articleSection":["Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/","name":"18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-19T22:18:51+00:00","dateModified":"2017-11-09T08:49:37+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-20-18\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"18. Pri\u00e8re des endeuill\u00e9s et r\u00e9citation du Qaddich des orphelins"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2775"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2775\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}