{"id":2799,"date":"2000-03-22T00:05:06","date_gmt":"2000-03-21T22:05:06","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2799"},"modified":"2017-11-09T11:34:16","modified_gmt":"2017-11-09T09:34:16","slug":"03-22-05","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/","title":{"rendered":"05. La <em>haftara<\/em>"},"content":{"rendered":"<p>Nos sages ont institu\u00e9, en plus de la lecture de la Torah, la lecture d\u2019un extrait des Proph\u00e8tes, extrait dont le th\u00e8me est connexe \u00e0 ce qui aura \u00e9t\u00e9 lu dans le rouleau de la Torah\u00a0; cette lecture des proph\u00e8tes est accompagn\u00e9e de b\u00e9n\u00e9dictions, une avant, quatre apr\u00e8s.<\/p>\n<p>Cette lecture fut institu\u00e9e suite \u00e0 un d\u00e9cret funeste\u00a0: \u00e0 l\u2019\u00e9poque du Deuxi\u00e8me Temple, il arriva que les autorit\u00e9s d\u2019occupation romaine interdirent aux Juifs d\u2019\u00e9tudier le Pentateuque. Comme on ne pouvait plus proc\u00e9der \u00e0 la lecture publique de la Torah le Chabbat, les sages d\u00e9cid\u00e8rent qu\u2019un passage des Proph\u00e8tes serait lu \u00e0 la place, \u00e0 la mani\u00e8re dont on lisait le Pentateuque\u00a0: on faisait monter sept appel\u00e9s, qui r\u00e9citaient les b\u00e9n\u00e9dictions de la Torah. Quand le mauvais d\u00e9cret fut annul\u00e9 et que l\u2019on proc\u00e9da de nouveau \u00e0 la lecture publique de la Torah chaque Chabbat, il fut d\u00e9cid\u00e9 de continuer \u00e0 lire le passage des Proph\u00e8tes. C\u2019est cette lecture que l\u2019on appelle <em>haftara<\/em> (\u00ab\u00a0conclusion\u00a0\u00bb), ainsi nomm\u00e9e parce que, par elle, on conclut la lecture de la Torah. Les sages institu\u00e8rent m\u00eame des b\u00e9n\u00e9dictions sp\u00e9cifiques pour accompagner la lecture des Proph\u00e8tes. Et dans la mesure o\u00f9, \u00e0 l\u2019\u00e9poque du d\u00e9cret funeste, sept personnes se succ\u00e9daient pour lire le passage des Proph\u00e8tes, chacun d\u2019eux lisant au moins trois versets, le lecteur de la <em>haftara<\/em> doit aujourd\u2019hui lire au moins vingt-et-un versets des Proph\u00e8tes. Toutefois, si le texte choisi n\u2019aborde le th\u00e8me vis\u00e9 qu\u2019en un moins grand nombre de versets, on peut s\u2019en contenter et s\u2019arr\u00eater l\u00e0 (<em>Choul\u2019han \u2018Aroukh<\/em>, <em>Ora\u2019h \u2018Ha\u00efm<\/em> 284, 1\u00a0; <em>Michna Beroura<\/em> 2).<\/p>\n<p>Pour que la <em>haftara<\/em> ne paraisse pas \u00e9gale en importance \u00e0 la lecture de la Torah, il a \u00e9t\u00e9 d\u00e9cid\u00e9 que le lecteur du passage proph\u00e9tique serait d\u2019abord appel\u00e9 \u00e0 la Torah, pour la r\u00e9p\u00e9tition des derniers versets de la paracha \u2013 passage appel\u00e9 <em>maftir<\/em> (c\u2019est-\u00e0-dire passage r\u00e9serv\u00e9 au \u00ab\u00a0lecteur de la conclusion\u00a0\u00bb) \u2013 puis lirait la <em>haftara<\/em> imm\u00e9diatement apr\u00e8s. De cette fa\u00e7on, il est clair que la lecture des livres proph\u00e9tiques en elle-m\u00eame n\u2019\u00e9quivaut pas \u00e0 la lecture de la Torah de Mo\u00efse, mais que, s\u2019appuyant sur ce que l\u2019on a lu dans le rouleau de la Torah, il est loisible d\u2019y ajouter la lecture d\u2019un fragment proph\u00e9tique.<\/p>\n<p>Selon certains avis, il faut que la<em> haftara<\/em> soit lue dans un livre des Proph\u00e8tes \u00e9crit \u00e0 l\u2019encre sur parchemin, \u00e0 la mani\u00e8re dont on lit la <em>paracha<\/em> dans un rouleau valide (tel est l\u2019avis du <em>Levouch<\/em>). Mais nombre de d\u00e9cisionnaires, parmi les A\u2019haronim, estiment que l\u2019on peut \u00e9galement lire la <em>haftara<\/em> dans un livre imprim\u00e9. A priori, il est bon d\u2019utiliser un ouvrage comprenant l\u2019ensemble du livre proph\u00e9tique d\u2019o\u00f9 la <em>haftara<\/em> de la semaine est tir\u00e9e\u00a0; mais a posteriori, on peut se contenter d\u2019un livre o\u00f9 ne sont imprim\u00e9s que les versets des diff\u00e9rentes <em>haftarot<\/em>, comme on le trouve dans nos \u00e9ditions du Pentateuque (<em>\u2018Houmach<\/em>) o\u00f9, apr\u00e8s chaque <em>paracha<\/em>, figure la <em>haftara <\/em>correspondante (<em>Michna Beroura<\/em> 284, 1).<\/p>\n<p>Le fid\u00e8le qui est appel\u00e9 en tant que <em>maftir<\/em> doit proc\u00e9der seul \u00e0 la lecture du passage proph\u00e9tique, tandis que l\u2019assembl\u00e9e l\u2019\u00e9coute. Celui qui voudrait lire \u00e0 voix basse en m\u00eame temps que le lecteur y est autoris\u00e9, \u00e0 condition de ne pas g\u00eaner l\u2019\u00e9coute de ses voisins (<em>Michna Beroura<\/em> 284, 11 et <em>B\u00e9our Halakha<\/em> ad loc.).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos sages ont institu\u00e9, en plus de la lecture de la Torah, la lecture d\u2019un extrait des Proph\u00e8tes, extrait dont le th\u00e8me est connexe \u00e0 ce qui aura \u00e9t\u00e9 lu dans le rouleau de la Torah\u00a0; cette lecture des proph\u00e8tes est accompagn\u00e9e de b\u00e9n\u00e9dictions, une avant, quatre apr\u00e8s. Cette lecture fut institu\u00e9e suite \u00e0 un [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2799","post","type-post","status-publish","format-standard","hentry","category-03-22"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>05. La haftara - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"05. La haftara - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Nos sages ont institu\u00e9, en plus de la lecture de la Torah, la lecture d\u2019un extrait des Proph\u00e8tes, extrait dont le th\u00e8me est connexe \u00e0 ce qui aura \u00e9t\u00e9 lu dans le rouleau de la Torah\u00a0; cette lecture des proph\u00e8tes est accompagn\u00e9e de b\u00e9n\u00e9dictions, une avant, quatre apr\u00e8s. Cette lecture fut institu\u00e9e suite \u00e0 un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-21T22:05:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T09:34:16+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-22-05\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-22-05\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"05. La haftara\",\"datePublished\":\"2000-03-21T22:05:06+00:00\",\"dateModified\":\"2017-11-09T09:34:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-22-05\\\/\"},\"wordCount\":622,\"articleSection\":[\"Chapitre 22 - Pri\u00e8re et Qidouch de Chabbat\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-22-05\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-22-05\\\/\",\"name\":\"05. La haftara - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-21T22:05:06+00:00\",\"dateModified\":\"2017-11-09T09:34:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-22-05\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-22-05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-22-05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"05. La haftara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"05. La haftara - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/","og_locale":"fr_FR","og_type":"article","og_title":"05. La haftara - Pnin\u00e9 Halakha","og_description":"Nos sages ont institu\u00e9, en plus de la lecture de la Torah, la lecture d\u2019un extrait des Proph\u00e8tes, extrait dont le th\u00e8me est connexe \u00e0 ce qui aura \u00e9t\u00e9 lu dans le rouleau de la Torah\u00a0; cette lecture des proph\u00e8tes est accompagn\u00e9e de b\u00e9n\u00e9dictions, une avant, quatre apr\u00e8s. Cette lecture fut institu\u00e9e suite \u00e0 un [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-21T22:05:06+00:00","article_modified_time":"2017-11-09T09:34:16+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"05. La haftara","datePublished":"2000-03-21T22:05:06+00:00","dateModified":"2017-11-09T09:34:16+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/"},"wordCount":622,"articleSection":["Chapitre 22 - Pri\u00e8re et Qidouch de Chabbat"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/","name":"05. La haftara - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-21T22:05:06+00:00","dateModified":"2017-11-09T09:34:16+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-22-05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-22-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"05. La haftara"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2799"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2799\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}