{"id":2821,"date":"2000-03-23T00:05:42","date_gmt":"2000-03-22T22:05:42","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2821"},"modified":"2017-11-09T12:09:09","modified_gmt":"2017-11-09T10:09:09","slug":"03-23-05","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/","title":{"rendered":"05. \u2018Hanouka"},"content":{"rendered":"<p>Comme nous l\u2019avons vu, les femmes sont tenues \u00e0 l\u2019allumage des lumi\u00e8res de \u2018Hanouka, car elles aussi ont b\u00e9n\u00e9fici\u00e9 du m\u00eame miracle. Une femme mari\u00e9e s\u2019acquitte de cette obligation par l\u2019allumage effectu\u00e9 par son mari, et une fille par l\u2019allumage de son p\u00e8re. Si le mari ou le p\u00e8re ne proc\u00e8de pas \u00e0 l\u2019allumage, parce qu\u2019il ne se trouve pas \u00e0 la maison, ou pour quelque autre raison, il revient \u00e0 l\u2019\u00e9pouse ou \u00e0 la fille d\u2019allumer les lumi\u00e8res. Bien entendu, une femme qui habite seule doit allumer les lumi\u00e8res de \u2018Hanouka par elle-m\u00eame.<\/p>\n<p>Selon la coutume ashk\u00e9naze, une fille qui habite chez son p\u00e8re est autoris\u00e9e \u00e0 allumer elle aussi les lumi\u00e8res de \u2018Hanouka, en r\u00e9citant la b\u00e9n\u00e9diction, bien que son p\u00e8re l\u2019ait d\u00e9j\u00e0 fait (cf. <em>Pnin\u00e9 Halakha<\/em>, <em>Zemanim<\/em> 12, 3-4, note 2).<\/p>\n<p>Les femmes ont coutume de ne pas accomplir de travaux pendant que br\u00fblent les lumi\u00e8res de \u2018Hanouka, tant que court le temps minimal prescrit pour leur combustion, cela pour deux raisons\u00a0: afin de manifester que ces lumi\u00e8res sont destin\u00e9es \u00e0 l\u2019accomplissement d\u2019une mitsva, et non \u00e0 un usage profane\u00a0; et parce que le miracle a commenc\u00e9 par l\u2019action de Judith, si bien que la f\u00eate de \u2018Hanouka a pour les femmes un statut plus \u00e9lev\u00e9 que pour les hommes, \u00e0 l\u2019exemple de \u2018Hol hamo\u2019ed o\u00f9 il est interdit de travailler<sup><a href='#_te01ftn23_c' id='_te01ftnref23_c' class='aup1'>[c]<\/a><\/sup>. Selon la premi\u00e8re raison, il est \u00e9galement interdit aux femmes de cuisiner des mets, bouillis ou frits, de crainte qu\u2019elles ne le fassent \u00e0 la lumi\u00e8re des bougies de \u2018Hanouka. Selon la seconde raison, seuls les travaux interdits \u00e0 \u2018Hol hamo\u2019ed, tels que la lessive ou la couture, sont interdits quand br\u00fblent les lumi\u00e8res de \u2018Hanouka, mais il est permis de faire bouillir ou frire des plats\u00a0; et tel est l\u2019usage le plus r\u00e9pandu. Quant aux familles o\u00f9 l\u2019on a coutume de s\u2019abstenir aussi de faire cuire des mets, on continuera d\u2019\u00eatre rigoureux, conform\u00e9ment \u00e0 sa coutume<sup><a href='#_te01ftn23_3' id='_te01ftnref23_3' class='aup1'>[3]<\/a><\/sup>.<\/p>\n<p>Selon certains d\u00e9cisionnaires, les femmes doivent r\u00e9citer le Hallel durant les jours de \u2018Hanouka, puisqu\u2019elles aussi ont b\u00e9n\u00e9fici\u00e9 du m\u00eame miracle et qu\u2019elles doivent cons\u00e9quemment louer Dieu pour cela. Toutefois, suivant la majorit\u00e9 des d\u00e9cisionnaires, elles n\u2019y sont pas oblig\u00e9es, et tel est l\u2019usage. Mais si l\u2019on souhaite apporter un suppl\u00e9ment de perfection \u00e0 sa pri\u00e8re, il est bon de r\u00e9citer le Hallel \u00e0 \u2018Hanouka. Selon la coutume ashk\u00e9naze, la femme le r\u00e9citera avec ses b\u00e9n\u00e9dictions\u00a0; selon la coutume s\u00e9farade, elle le r\u00e9citera sans b\u00e9n\u00e9diction<sup><a href='#_te01ftn23_4' id='_te01ftnref23_4' class='aup1'>[4]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref23_c' id='_te01ftn23_c'>[c]<\/a>. L\u2019interdit du travail n\u2019est pas aussi rigoureux aux jours interm\u00e9diaires de \u2018Hol hamo\u2019ed que durant les jours ch\u00f4m\u00e9s de Yom tov, mais la possibilit\u00e9 d\u2019y travailler est soumise \u00e0 des conditions pr\u00e9cises.<\/li>\n<p><a href='#_te01ftnref23_3' id='_te01ftn23_3'>[3]<\/a>. Cf. <em>Choul\u2019han \u2018Aroukh<\/em> 670, 1, <em>Michna Beroura<\/em> 4, <em>Halikhot Beitah<\/em> 23, 14 et <em>Halikhot Bat Isra\u00ebl <\/em>21, 14. L\u2019usage courant est d\u2019\u00eatre indulgent, et tel est l\u2019avis que nous avons entendu de la part du Rav Mordekha\u00ef Elyahou \u2013 que la m\u00e9moire du juste soit b\u00e9nie. Cf. <em>Pnin\u00e9 Halakha<\/em>, <em>Zemanim<\/em> 11, 11.<\/li>\n<p><a href='#_te01ftnref23_4' id='_te01ftn23_4'>[4]<\/a>. Plusieurs A\u2019haronim inf\u00e8rent de <em>Tossephot <\/em>sur <em>Souka<\/em> 38b que les femmes doivent r\u00e9citer le Hallel \u00e0 \u2018Hanouka, en raison du fait qu\u2019<em>elles aussi ont b\u00e9n\u00e9fici\u00e9 du m\u00eame miracle<\/em>, et qu\u2019elles doivent donc, elles aussi, louer Dieu pour cela, de m\u00eame qu\u2019elles sont tenues de r\u00e9citer le Hallel le soir de Pessa\u2019h. Telle est la position du <em>Torat Repha\u00ebl<\/em>, <em>Ora\u2019h \u2018Ha\u00efm<\/em> 75, du <em>Hit\u2019orerout Techouva<\/em> et du <em>Binyan Chelomo<\/em> VIII, 63. Mais selon la majorit\u00e9 des d\u00e9cisionnaires \u2013 et conform\u00e9ment \u00e0 Ma\u00efmonide, <em>Hilkhot \u2018Hanouka<\/em> 3, 6 \u2013, les femmes sont dispens\u00e9es de la r\u00e9citation du Hallel \u00e0 \u2018Hanouka, car il s\u2019agit d\u2019une mitsva conditionn\u00e9e par le temps.<\/li>\n<p>On peut soutenir que les femmes s\u2019acquittent d\u00e9j\u00e0, par l\u2019allumage des lumi\u00e8res, de l\u2019obligation de louer Dieu\u00a0; et la chose est vraisemblable car, durant de nombreuses g\u00e9n\u00e9rations, la plupart des femmes ne savaient pas r\u00e9citer le Hallel, or il est difficile de soutenir que, tout en y \u00e9tant oblig\u00e9es, elles ne s\u2019en acquittaient pas. Simplement, tout ce qui est li\u00e9 au rituel des pri\u00e8res synagogales, lequel d\u00e9pend du temps, n\u2019oblige pas les femmes, et si elles sont tenues de r\u00e9citer le Hallel le soir de Pessa\u2019h, c\u2019est parce qu\u2019il fait alors partie de la soir\u00e9e pascale, \u00e0 laquelle les femmes sont oblig\u00e9es par la Torah, et parce que tout ce que les sages ont prescrit aux hommes pour ladite soir\u00e9e, ils l\u2019ont aussi prescrit aux femmes. Cf. <em>Ye\u2019hav\u00e9 Da\u2019at<\/em> I, 78, <em>Halikhot Chelomo<\/em>, <em>Mo\u2019adim<\/em> II, 17, 6, <em>Halikhot Beitah<\/em> 8, 5 et notes.<\/p>\n<p>Selon Ma\u00efmonide (<em>\u2018Hanouka<\/em> 3, 6), puisque les femmes sont dispens\u00e9es de r\u00e9citer le Hallel, elles ne peuvent acquitter de leur obligation les hommes, qui sont, pour leur part, tenus de le dire. De prime abord, telle est aussi la r\u00e8gle pour le Hallel de Roch \u2018hodech, et c\u2019est ce qui ressort du <em>Maguen Avraham<\/em> 422, 5. Toutefois, selon le <em>B\u00e9our Halakha<\/em> 422 (\u05d3\u00a0\u00bb\u05d4 \u05d4\u05dc\u05dc), puisque le Hallel de Roch \u2018hodech est un usage et non une obligation, une femme peut en acquitter un homme car, fondamentalement, l\u2019un et l\u2019autre en sont dispens\u00e9s.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Comme nous l\u2019avons vu, les femmes sont tenues \u00e0 l\u2019allumage des lumi\u00e8res de \u2018Hanouka, car elles aussi ont b\u00e9n\u00e9fici\u00e9 du m\u00eame miracle. Une femme mari\u00e9e s\u2019acquitte de cette obligation par l\u2019allumage effectu\u00e9 par son mari, et une fille par l\u2019allumage de son p\u00e8re. Si le mari ou le p\u00e8re ne proc\u00e8de pas \u00e0 l\u2019allumage, parce [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-2821","post","type-post","status-publish","format-standard","hentry","category-03-23"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>05. \u2018Hanouka - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"05. \u2018Hanouka - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Comme nous l\u2019avons vu, les femmes sont tenues \u00e0 l\u2019allumage des lumi\u00e8res de \u2018Hanouka, car elles aussi ont b\u00e9n\u00e9fici\u00e9 du m\u00eame miracle. Une femme mari\u00e9e s\u2019acquitte de cette obligation par l\u2019allumage effectu\u00e9 par son mari, et une fille par l\u2019allumage de son p\u00e8re. Si le mari ou le p\u00e8re ne proc\u00e8de pas \u00e0 l\u2019allumage, parce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-22T22:05:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T10:09:09+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-05\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-05\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"05. \u2018Hanouka\",\"datePublished\":\"2000-03-22T22:05:42+00:00\",\"dateModified\":\"2017-11-09T10:09:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-05\\\/\"},\"wordCount\":933,\"articleSection\":[\"Chapitre 23 - Quelques r\u00e8gles relatives aux f\u00eates\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-05\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-05\\\/\",\"name\":\"05. \u2018Hanouka - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-22T22:05:42+00:00\",\"dateModified\":\"2017-11-09T10:09:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-05\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"05. \u2018Hanouka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"05. \u2018Hanouka - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/","og_locale":"fr_FR","og_type":"article","og_title":"05. \u2018Hanouka - Pnin\u00e9 Halakha","og_description":"Comme nous l\u2019avons vu, les femmes sont tenues \u00e0 l\u2019allumage des lumi\u00e8res de \u2018Hanouka, car elles aussi ont b\u00e9n\u00e9fici\u00e9 du m\u00eame miracle. Une femme mari\u00e9e s\u2019acquitte de cette obligation par l\u2019allumage effectu\u00e9 par son mari, et une fille par l\u2019allumage de son p\u00e8re. Si le mari ou le p\u00e8re ne proc\u00e8de pas \u00e0 l\u2019allumage, parce [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-22T22:05:42+00:00","article_modified_time":"2017-11-09T10:09:09+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"05. \u2018Hanouka","datePublished":"2000-03-22T22:05:42+00:00","dateModified":"2017-11-09T10:09:09+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/"},"wordCount":933,"articleSection":["Chapitre 23 - Quelques r\u00e8gles relatives aux f\u00eates"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/","name":"05. \u2018Hanouka - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-22T22:05:42+00:00","dateModified":"2017-11-09T10:09:09+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-23-05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"05. \u2018Hanouka"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2821"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2821\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}