{"id":2842,"date":"2000-03-23T00:09:54","date_gmt":"2000-03-22T22:09:54","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2842"},"modified":"2017-11-09T12:27:14","modified_gmt":"2017-11-09T10:27:14","slug":"03-23-09","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/","title":{"rendered":"09. Nuit du <strong>s\u00e9der<\/strong>"},"content":{"rendered":"<p>Les femmes sont tenues d\u2019accomplir l\u2019ensemble des commandements de la soir\u00e9e du <strong>s\u00e9der<\/strong> (la soir\u00e9e pascale, au premier soir de la f\u00eate de Pessa\u2019h)\u00a0: le r\u00e9cit de la sortie d\u2019Egypte, la consommation de la <strong>matsa<\/strong> (pain azyme), du <strong>maror<\/strong> (herbes am\u00e8res) et des quatre coupes de vin, car \u00ab\u00a0elles aussi ont b\u00e9n\u00e9fici\u00e9 du m\u00eame miracle\u00a0\u00bb (<strong>Pessa\u2019him<\/strong> 108b\u00a0; <strong>Choul\u2019han \u2018Aroukh<\/strong> 472, 14\u00a0; <strong>Michna Beroura<\/strong> 479, 9\u00a0; cf. supra \u00a7 4).<\/p>\n<p>Suivant ce m\u00eame principe, les femmes se doivent aussi de r\u00e9citer le Hallel\u00a0; c\u2019est la seule fois dans l\u2019ann\u00e9e que les femmes ont une telle obligation (<strong>Tossephot <\/strong>sur <strong>Souka<\/strong> 38a)<sup><a href='#_te01ftn23_9' id='_te01ftnref23_9' class='aup1'>[9]<\/a><\/sup>.<\/p>\n<p>A priori, les femmes doivent s\u2019accouder au moment de manger le pain azyme et de boire les quatre coupes\u00a0; toutefois, si elles ont oubli\u00e9 de s\u2019accouder, elles n\u2019ont pas besoin de r\u00e9p\u00e9ter cette consommation. Mais il est bon, pour des femmes \u00ab\u00a0distingu\u00e9es\u00a0\u00bb, de r\u00e9p\u00e9ter leur consommation du pain azyme dans le cas o\u00f9 elles auraient oubli\u00e9 de s\u2019accouder pour manger celui-ci<sup><a href='#_te01ftn23_10' id='_te01ftnref23_10' class='aup1'>[10]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref23_9' id='_te01ftn23_9'>[9]<\/a>. Selon le <strong>Ye\u2019hav\u00e9 Da\u2019at<\/strong> 5, 34, m\u00eame une femme qui reste chez elle au moment de l\u2019office du soir de Pessa\u2019h doit r\u00e9citer le Hallel assorti de ses b\u00e9n\u00e9dictions <strong>avant<\/strong> le commencement du <strong>s\u00e9der<\/strong>, tout comme les hommes ont coutume de le dire \u00e0 la synagogue. En effet, ce Hallel est r\u00e9cit\u00e9 pour remercier Dieu du miracle de la sortie d\u2019Egypte\u00a0; cela, selon la coutume s\u00e9farade, telle qu\u2019elle est rapport\u00e9e par le <strong>Choul\u2019han \u2018Aroukh<\/strong> 487, 4. En revanche, selon la coutume ashk\u00e9naze, on n\u2019a pas l\u2019usage de r\u00e9citer le Hallel \u00e0 la synagogue le soir de Pessa\u2019h, comme le rapporte le Rama ad loc. Si l\u2019on s\u2019en tient m\u00eame \u00e0 la coutume s\u00e9farade, certains d\u00e9cisionnaires sont d\u2019avis que le particulier n\u2019a pas lieu de r\u00e9citer le Hallel, comme l\u2019\u00e9crit le <strong>Beit Yehouda\u00a0<\/strong>; d\u2019apr\u00e8s cela, les femmes qui se trouvent chez elles ne le r\u00e9citent pas non plus. En pratique, puisqu\u2019il s\u2019agit d\u2019un cas de doute portant sur une norme rabbinique, la r\u00e8gle est conforme \u00e0 l\u2019opinion indulgente, et les femmes sont dispens\u00e9es de r\u00e9citer le Hallel avant le s\u00e9der. Cf. <strong>Miqra\u00e9 Qodech<\/strong> du Rav Harari 3, notes 18 et 19, o\u00f9 l\u2019on voit que, jadis, de nombreuses femmes ne savaient pas lire, et qu\u2019il n\u2019est donc pas vraisemblable que les sages leur aient prescrit de r\u00e9citer le Hallel, seules \u00e0 la maison.<\/li>\n<p><a href='#_te01ftnref23_10' id='_te01ftn23_10'>[10]<\/a>. Dans le trait\u00e9 <strong>Pessa\u2019him <\/strong>108a, il appara\u00eet que la femme, chez son mari, n\u2019est pas tenue de s\u2019accouder\u00a0; mais que s\u2019il s\u2019agit d\u2019une femme \u00ab\u00a0importante\u00a0\u00bb, elle le doit. Le <strong>Choul\u2019han \u2018Aroukh<\/strong> 472, 4 rapporte la r\u00e8gle en ces termes. La raison en est que, si le fait de s\u2019accouder, \u00e0 la mani\u00e8re d\u2019hommes libres, ne procure pas un sentiment de libert\u00e9 int\u00e9rieure, cela n\u2019a pas d\u2019utilit\u00e9. D\u00e8s lors, un \u00e9l\u00e8ve chez son rabbin ne s\u2019accoude pas non plus sans sa permission [car il n\u2019est pas avec lui dans une relation d\u2019\u00e9galit\u00e9. Or les femmes autres que particuli\u00e8rement distingu\u00e9es sur le plan social avaient autrefois un sentiment de suj\u00e9tion \u00e0 l\u2019\u00e9gard des hommes.] Plusieurs avis sont en pr\u00e9sence quant \u00e0 la d\u00e9finition de ce qu\u2019est une femme \u00ab\u00a0importante\u00a0\u00bb\u00a0: selon certains, il s\u2019agit d\u2019une femme qui n\u2019est pas soumise \u00e0 son mari, ou qui est riche, ou dot\u00e9e d\u2019une ascendance prestigieuse, ou encore une femme dont le mari n\u2019est pas pointilleux en cette mati\u00e8re. Le Rama \u00e9crit qu\u2019\u00e0 pr\u00e9sent toutes nos femmes sont importantes, mais qu\u2019elles ont pris pour coutume d\u2019\u00eatre indulgentes et de ne pas s\u2019accouder, conform\u00e9ment \u00e0 l\u2019opinion du Raavia, d\u2019apr\u00e8s lequel, de nos jours, on n\u2019a plus l\u2019habitude de s\u2019accouder lors des repas importants, si bien qu\u2019\u00e0 son avis il n\u2019y a plus de n\u00e9cessit\u00e9 de s\u2019accouder pendant le <strong>s\u00e9der<\/strong>.<\/li>\n<p>En pratique, il convient que toutes les femmes, quelle que soit leur communaut\u00e9 d\u2019origine, s\u2019efforcent de s\u2019accouder, car nous n\u2019avons pas coutume de nous appuyer en cela sur l\u2019opinion du Raavia. Tel est l\u2019avis du <strong>Knesset Haguedola<\/strong> et du <strong>Kaf Ha\u2019ha\u00efm<\/strong> 28\u00a0; et tel est l\u2019usage de nombreuses femmes d\u2019origine ashk\u00e9naze. Simplement, quand une femme ne s\u2019est pas accoud\u00e9e, elle n\u2019a pas besoin de r\u00e9p\u00e9ter sa consommation, car l\u2019exigence de l\u2019accoudement est rabbinique, et certains d\u00e9cisionnaires estiment que les femmes n\u2019y sont pas oblig\u00e9es, soit qu\u2019elles ne r\u00e9pondent pas \u00e0 la d\u00e9finition de la \u00ab\u00a0femme importante\u00a0\u00bb, soit parce que les femmes ont adopt\u00e9, dans leur ensemble, l\u2019usage du Raavia. Cf. <strong>\u2018Hazon \u2018Ovadia<\/strong> chap. 14. En tout \u00e9tat de cause, il semble que, s\u2019agissant de la consommation d\u2019un <strong>kaza\u00eft<\/strong> [entre 25 et 50 cm\u00b3, selon les opinions] de pain azyme, obligation de rang toranique, il convienne aux femmes qui s\u2019estiment \u00ab\u00a0distingu\u00e9es\u00a0\u00bb d\u2019\u00eatre rigoureuses et de ne pas s\u2019appuyer sur l\u2019opinion du Raavia. (Cette note reproduit celle du tome de <strong>Pnin\u00e9 Halakha<\/strong> consacr\u00e9 \u00e0 la f\u00eate de Pessa\u2019h, chap. 16, note 9.)<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les femmes sont tenues d\u2019accomplir l\u2019ensemble des commandements de la soir\u00e9e du s\u00e9der (la soir\u00e9e pascale, au premier soir de la f\u00eate de Pessa\u2019h)\u00a0: le r\u00e9cit de la sortie d\u2019Egypte, la consommation de la matsa (pain azyme), du maror (herbes am\u00e8res) et des quatre coupes de vin, car \u00ab\u00a0elles aussi ont b\u00e9n\u00e9fici\u00e9 du m\u00eame miracle\u00a0\u00bb [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-2842","post","type-post","status-publish","format-standard","hentry","category-03-23"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>09. Nuit du s\u00e9der - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"09. Nuit du s\u00e9der - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Les femmes sont tenues d\u2019accomplir l\u2019ensemble des commandements de la soir\u00e9e du s\u00e9der (la soir\u00e9e pascale, au premier soir de la f\u00eate de Pessa\u2019h)\u00a0: le r\u00e9cit de la sortie d\u2019Egypte, la consommation de la matsa (pain azyme), du maror (herbes am\u00e8res) et des quatre coupes de vin, car \u00ab\u00a0elles aussi ont b\u00e9n\u00e9fici\u00e9 du m\u00eame miracle\u00a0\u00bb [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-22T22:09:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T10:27:14+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-09\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-09\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"09. Nuit du s\u00e9der\",\"datePublished\":\"2000-03-22T22:09:54+00:00\",\"dateModified\":\"2017-11-09T10:27:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-09\\\/\"},\"wordCount\":911,\"articleSection\":[\"Chapitre 23 - Quelques r\u00e8gles relatives aux f\u00eates\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-09\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-09\\\/\",\"name\":\"09. Nuit du s\u00e9der - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-22T22:09:54+00:00\",\"dateModified\":\"2017-11-09T10:27:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-09\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-09\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-09\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"09. Nuit du s\u00e9der\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"09. Nuit du s\u00e9der - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/","og_locale":"fr_FR","og_type":"article","og_title":"09. Nuit du s\u00e9der - Pnin\u00e9 Halakha","og_description":"Les femmes sont tenues d\u2019accomplir l\u2019ensemble des commandements de la soir\u00e9e du s\u00e9der (la soir\u00e9e pascale, au premier soir de la f\u00eate de Pessa\u2019h)\u00a0: le r\u00e9cit de la sortie d\u2019Egypte, la consommation de la matsa (pain azyme), du maror (herbes am\u00e8res) et des quatre coupes de vin, car \u00ab\u00a0elles aussi ont b\u00e9n\u00e9fici\u00e9 du m\u00eame miracle\u00a0\u00bb [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-22T22:09:54+00:00","article_modified_time":"2017-11-09T10:27:14+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"09. Nuit du s\u00e9der","datePublished":"2000-03-22T22:09:54+00:00","dateModified":"2017-11-09T10:27:14+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/"},"wordCount":911,"articleSection":["Chapitre 23 - Quelques r\u00e8gles relatives aux f\u00eates"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/","name":"09. Nuit du s\u00e9der - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-22T22:09:54+00:00","dateModified":"2017-11-09T10:27:14+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-23-09\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-09\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"09. Nuit du s\u00e9der"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2842"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2842\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}