{"id":2846,"date":"2000-03-23T00:11:30","date_gmt":"2000-03-22T22:11:30","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2846"},"modified":"2017-11-09T12:28:57","modified_gmt":"2017-11-09T10:28:57","slug":"03-23-11","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/","title":{"rendered":"11. B\u00e9n\u00e9diction des arbres en fleurs (<strong>Birkat ha-ilanot<\/strong>)"},"content":{"rendered":"<p>Quand, au mois de Nissan, on voit des arbres fruitiers en fleurs, on r\u00e9cite la b\u00e9n\u00e9diction\u00a0: \u00ab\u00a0B\u00e9ni sois-Tu, Eternel, notre Dieu, roi de l\u2019univers, qui as pourvu le monde sans que rien n\u2019y manque, y cr\u00e9ant de bonnes cr\u00e9atures et de bons arbres pour la jouissance des hommes\u00a0\u00bb (<strong>Choul\u2019han \u2018Aroukh<\/strong>, <strong>Ora\u2019h \u2018Ha\u00efm<\/strong> 225, 1).<\/p>\n<p>Il est juste que les femmes, elles aussi, r\u00e9citent cette b\u00e9n\u00e9diction. Et bien que celle-ci soit sp\u00e9cifiquement li\u00e9e au mois de Nissan, les d\u00e9cisionnaires expliquent que cette obligation n\u2019est pas consid\u00e9r\u00e9e comme conditionn\u00e9e par le temps. En effet, de l\u2019avis de nombreux auteurs, on peut prononcer cette b\u00e9n\u00e9diction en voyant des arbres en fleurs un autre mois. M\u00eame pour ceux qui estiment que ce n\u2019est qu\u2019en Nissan que l\u2019on r\u00e9cite cette b\u00e9n\u00e9diction, ce n\u2019est pas parce que le temps de sa r\u00e9citation serait d\u00e9pendant du mois de Nissan, mais bien parce que les fleurs apparaissent pr\u00e9cis\u00e9ment durant ce mois, ce qui a conduit les sages \u00e0 prescrire cette r\u00e9citation au mois de Nissan. On voit donc que la b\u00e9n\u00e9diction est conditionn\u00e9e par l\u2019apparition des fleurs et non par le temps<sup><a href='#_te01ftn23_11' id='_te01ftnref23_11' class='aup1'>[11]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref23_11' id='_te01ftn23_11'>[11]<\/a>. Selon le Ritva, on peut aussi bien dire cette b\u00e9n\u00e9diction avant qu\u2019apr\u00e8s le mois de Nissan, et telle est aussi l\u2019opinion de la majorit\u00e9 des d\u00e9cisionnaires, si bien que, a posteriori, on peut s\u2019appuyer sur cette opinion, comme l\u2019explique le <strong>Ye\u2019hav\u00e9 Da\u2019at<\/strong> I, 1. Dans ces conditions, cette b\u00e9n\u00e9diction n\u2019est pas d\u00e9pendante du temps mais de la saison de floraison des arbres fruitiers. Pour ceux-l\u00e0 m\u00eame qui estiment qu\u2019elle est conditionn\u00e9e par le temps, elle ne fait pas partie, selon le <strong>Tour\u00e9 Even<\/strong> sur <strong>M\u00e9guila<\/strong> 20b, de la cat\u00e9gorie formelle des obligations temporelles, car elle est conditionn\u00e9e par l\u2019apparition des fleurs, lesquelles se trouvent appara\u00eetre en Nissan, raison pour laquelle les sages ont \u00e9tabli le temps de la b\u00e9n\u00e9diction durant ce mois. C\u2019est ce qu\u2019\u00e9crivent le <strong>Har Tsvi<\/strong>, <strong>Ora\u2019h \u2018Ha\u00efm<\/strong> 1, 118, le <strong>\u2018Hazon \u2018Ovadia<\/strong> p. 8 et le <strong>Halikhot Beitah<\/strong> 13, 23.<\/li>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quand, au mois de Nissan, on voit des arbres fruitiers en fleurs, on r\u00e9cite la b\u00e9n\u00e9diction\u00a0: \u00ab\u00a0B\u00e9ni sois-Tu, Eternel, notre Dieu, roi de l\u2019univers, qui as pourvu le monde sans que rien n\u2019y manque, y cr\u00e9ant de bonnes cr\u00e9atures et de bons arbres pour la jouissance des hommes\u00a0\u00bb (Choul\u2019han \u2018Aroukh, Ora\u2019h \u2018Ha\u00efm 225, 1). Il [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-2846","post","type-post","status-publish","format-standard","hentry","category-03-23"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>11. B\u00e9n\u00e9diction des arbres en fleurs (Birkat ha-ilanot) - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"11. B\u00e9n\u00e9diction des arbres en fleurs (Birkat ha-ilanot) - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Quand, au mois de Nissan, on voit des arbres fruitiers en fleurs, on r\u00e9cite la b\u00e9n\u00e9diction\u00a0: \u00ab\u00a0B\u00e9ni sois-Tu, Eternel, notre Dieu, roi de l\u2019univers, qui as pourvu le monde sans que rien n\u2019y manque, y cr\u00e9ant de bonnes cr\u00e9atures et de bons arbres pour la jouissance des hommes\u00a0\u00bb (Choul\u2019han \u2018Aroukh, Ora\u2019h \u2018Ha\u00efm 225, 1). Il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-22T22:11:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T10:28:57+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-11\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-11\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"11. B\u00e9n\u00e9diction des arbres en fleurs (Birkat ha-ilanot)\",\"datePublished\":\"2000-03-22T22:11:30+00:00\",\"dateModified\":\"2017-11-09T10:28:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-11\\\/\"},\"wordCount\":396,\"articleSection\":[\"Chapitre 23 - Quelques r\u00e8gles relatives aux f\u00eates\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-11\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-11\\\/\",\"name\":\"11. B\u00e9n\u00e9diction des arbres en fleurs (Birkat ha-ilanot) - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-22T22:11:30+00:00\",\"dateModified\":\"2017-11-09T10:28:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-11\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-11\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-23-11\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"11. B\u00e9n\u00e9diction des arbres en fleurs (Birkat ha-ilanot)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"11. B\u00e9n\u00e9diction des arbres en fleurs (Birkat ha-ilanot) - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/","og_locale":"fr_FR","og_type":"article","og_title":"11. B\u00e9n\u00e9diction des arbres en fleurs (Birkat ha-ilanot) - Pnin\u00e9 Halakha","og_description":"Quand, au mois de Nissan, on voit des arbres fruitiers en fleurs, on r\u00e9cite la b\u00e9n\u00e9diction\u00a0: \u00ab\u00a0B\u00e9ni sois-Tu, Eternel, notre Dieu, roi de l\u2019univers, qui as pourvu le monde sans que rien n\u2019y manque, y cr\u00e9ant de bonnes cr\u00e9atures et de bons arbres pour la jouissance des hommes\u00a0\u00bb (Choul\u2019han \u2018Aroukh, Ora\u2019h \u2018Ha\u00efm 225, 1). Il [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-22T22:11:30+00:00","article_modified_time":"2017-11-09T10:28:57+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"11. B\u00e9n\u00e9diction des arbres en fleurs (Birkat ha-ilanot)","datePublished":"2000-03-22T22:11:30+00:00","dateModified":"2017-11-09T10:28:57+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/"},"wordCount":396,"articleSection":["Chapitre 23 - Quelques r\u00e8gles relatives aux f\u00eates"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/","name":"11. B\u00e9n\u00e9diction des arbres en fleurs (Birkat ha-ilanot) - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-22T22:11:30+00:00","dateModified":"2017-11-09T10:28:57+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-23-11\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-23-11\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"11. B\u00e9n\u00e9diction des arbres en fleurs (Birkat ha-ilanot)"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2846"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2846\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}