{"id":3150,"date":"2016-05-09T00:04:27","date_gmt":"2016-05-08T21:04:27","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=3150"},"modified":"2018-03-18T12:03:59","modified_gmt":"2018-03-18T10:03:59","slug":"05-09-04","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/","title":{"rendered":"04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat"},"content":{"rendered":"<p>Il est de r\u00e8gle qu\u2019il n\u2019y a point de deuil le Chabbat. Aussi, m\u00eame si le 9 av tombe un Chabbat, le je\u00fbne est repouss\u00e9 au dimanche\u00a0; et ce Chabbat, on mange de la viande, on boit du vin, et l\u2019on peut m\u00eame servir un repas digne de Salomon dans toute sa gloire. De m\u00eame, on chante des cantiques de Chabbat, comme \u00e0 l\u2019habitude, puisqu\u2019il n\u2019y a pas de deuil pendant Chabbat. Bien entendu, la r\u00e8gle est la m\u00eame si le 9 av tombe le dimanche\u00a0: le Chabbat pr\u00e9c\u00e9dent, on se conduit comme chaque Chabbat. Mais entre le Chabbat et le commencement du je\u00fbne, il y a un temps interm\u00e9diaire, durant lequel le Chabbat n\u2019est pas encore achev\u00e9 et, en revanche, les interdits li\u00e9s au je\u00fbne s\u2019appliquent d\u00e9j\u00e0. Cela s\u2019explique par le fait qu\u2019un doute existe quant au moment exact o\u00f9 se termine le jour pr\u00e9c\u00e9dent et ou commence le jour nouveau\u00a0: est-ce au coucher du soleil (<em>cheqi\u2019at ha\u2019hama<\/em>), ou \u00e0 la tomb\u00e9e de la nuit (<em>tset hakokhavim<\/em>, \u00ab\u00a0sortie des \u00e9toiles\u00a0\u00bb)\u00a0? Aussi, la p\u00e9riode qui s\u00e9pare le coucher du soleil de la tomb\u00e9e de la nuit est-elle douteuse\u00a0: elle rel\u00e8ve peut-\u00eatre du jour, peut-\u00eatre de la nuit. On appelle cette p\u00e9riode <em>bein hachmachot<\/em> (cr\u00e9puscule, litt. \u00ab\u00a0entre les soleils\u00a0\u00bb). Or, comme il existe une mitsva d\u2019ajouter du temps au Chabbat (mitsva de <em>toss\u00e9fet Chabbat<\/em>), celui-ci se prolonge quelques minutes encore apr\u00e8s la tomb\u00e9e de la nuit. En cons\u00e9quence, la p\u00e9riode qui va du coucher du soleil aux quelques minutes suivant la tomb\u00e9e de la nuit est une p\u00e9riode commune au Chabbat et au je\u00fbne. Durant cette p\u00e9riode, il est interdit de faire un acte qui serait regard\u00e9 comme une coutume de deuil, puisqu\u2019il n\u2019y a pas de deuil le Chabbat\u00a0; mais en revanche, d\u00e8s le coucher du soleil, on s\u2019abstient des choses qui ne sont pas indispensables au Chabbat, telles que manger, boire, se laver et s\u2019oindre.<\/p>\n<p>Par cons\u00e9quent, \u00e0 la <em>s\u00e9\u2019ouda chelichit<\/em> (le troisi\u00e8me repas sabbatique), on mange comme on le fait chaque Chabbat, et l\u2019on chante des cantiques sabbatiques comme \u00e0 l\u2019accoutum\u00e9e. Simplement, on s\u2019arr\u00eate de manger et de boire avant le coucher du soleil, puisqu\u2019il n\u2019y a pas d\u2019obligation, du point de vue du Chabbat, \u00e0 continuer de manger, durant ce troisi\u00e8me repas, apr\u00e8s le coucher du soleil (<em>Choul\u2019han \u2018Aroukh<\/em> 552, 10, <em>Michna Beroura <\/em>23). De m\u00eame, il convient de ne plus chanter de cantiques joyeux \u00e0 partir du coucher du soleil\u00a0; il n\u2019y a pas, en cela, de signe de deuil, puisque, de toute fa\u00e7on, on n\u2019a pas l\u2019usage d\u2019entonner des chants de joie \u00e0 toute heure du Chabbat. Dans le m\u00eame ordre d\u2019id\u00e9es, on s\u2019abstient de se laver et de s\u2019oindre, d\u00e8s le coucher du soleil, puisque, de toute fa\u00e7on, on ne se lave pas \u00e0 toute heure du Chabbat. Toutefois, si l\u2019on est all\u00e9 aux toilettes durant cette p\u00e9riode cr\u00e9pusculaire, on se lavera les mains comme d\u2019habitude, car ne pas le faire reviendrait \u00e0 s\u2019endeuiller pendant Chabbat.<\/p>\n<p>On garde ses v\u00eatements sabbatiques et ses chaussures, m\u00eame si elles sont en cuir, on reste assis sur sa chaise, et l\u2019on continue de se saluer en disant <em>chalom<\/em>, jusqu\u2019\u00e0 ce qu\u2019apparaissent trois \u00e9toiles moyennes dans le ciel et qu\u2019expirent encore quelques minutes, en tant que suppl\u00e9ment au Chabbat (<em>toss\u00e9fet Chabbat<\/em>) (conform\u00e9ment \u00e0 l\u2019heure de sortie de Chabbat indiqu\u00e9e dans les calendriers). Alors, on doit dire les mots <em>Baroukh hamavdil bein qodech le\u2019hol<\/em> (\u00ab\u00a0B\u00e9ni soit Celui qui distingue le saint du profane\u00a0\u00bb)\u00a0; par cette formule, on se s\u00e9pare du Chabbat. Apr\u00e8s cela, on retire ses chaussures de cuir, on quitte ses v\u00eatements sabbatiques, et l\u2019on met des v\u00eatements de semaine. Il faut mettre des v\u00eatements que l\u2019on avait d\u00e9j\u00e0 port\u00e9s durant la semaine \u00e9coul\u00e9e, car il ne faut pas porter de v\u00eatements lessiv\u00e9s, le 9 av<sup><a href='#_te01ftn9_3' id='_te01ftnref9_3' class='aup1'>[3]<\/a><\/sup>.<\/p>\n<p>On a l\u2019usage de retarder l\u2019office d\u2019Arvit, \u00e0 l\u2019issue de Chabbat, d\u2019un quart d\u2019heure environ, afin que tous les fid\u00e8les aient le temps de prendre cong\u00e9 du Chabbat, \u00e0 leur domicile, de quitter leur chaussures de cuir, de se changer, et de se rendre \u00e0 la synagogue pour l\u2019office d\u2019Arvit et la lecture du rouleau d\u2019<em>Eikha<\/em> (les Lamentations) en v\u00eatements de semaine.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref9_3' id='_te01ftn9_3'>[3]<\/a>. Certains ont coutume de retirer leurs chaussures de cuir d\u00e8s le coucher du soleil, \u00e0 condition de ne pas ressentir, en faisant cela, que ce retrait exprime le deuil. Cependant, la coutume la plus r\u00e9pandue consiste \u00e0 retirer ses chaussures de cuir apr\u00e8s la tomb\u00e9e de la nuit. Cf. <em>Hilkhot \u2018Hag Be\u2019hag<\/em> 8, notes 2 et 7, qui se fonde sur le Gaon de Vilna pour expliquer que l\u2019on ne se fait pas souffrir le Chabbat\u00a0; d\u2019apr\u00e8s cela, l\u2019auteur estime m\u00eame qu\u2019il est permis de se laver et de s\u2019oindre jusqu\u2019\u00e0 l\u2019issue de Chabbat. Mais suivant la coutume g\u00e9n\u00e9ralement observ\u00e9e, il y a lieu de s\u2019abstenir de tout ce qui n\u2019est pas reconnaissable comme expression de deuil. Aussi, a priori, il ne faut ni se laver ni s\u2019oindre\u00a0; mais si l\u2019on sort des toilettes, on se lavera les mains de la mani\u00e8re habituelle, c\u2019est-\u00e0-dire en mouillant toute la main, et non pas seulement les doigts comme on le fait le 9 av.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il est de r\u00e8gle qu\u2019il n\u2019y a point de deuil le Chabbat. Aussi, m\u00eame si le 9 av tombe un Chabbat, le je\u00fbne est repouss\u00e9 au dimanche\u00a0; et ce Chabbat, on mange de la viande, on boit du vin, et l\u2019on peut m\u00eame servir un repas digne de Salomon dans toute sa gloire. De m\u00eame, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[152],"tags":[],"class_list":["post-3150","post","type-post","status-publish","format-standard","hentry","category-05-09"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Il est de r\u00e8gle qu\u2019il n\u2019y a point de deuil le Chabbat. Aussi, m\u00eame si le 9 av tombe un Chabbat, le je\u00fbne est repouss\u00e9 au dimanche\u00a0; et ce Chabbat, on mange de la viande, on boit du vin, et l\u2019on peut m\u00eame servir un repas digne de Salomon dans toute sa gloire. De m\u00eame, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-08T21:04:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-18T10:03:59+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-09-04\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-09-04\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat\",\"datePublished\":\"2016-05-08T21:04:27+00:00\",\"dateModified\":\"2018-03-18T10:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-09-04\\\/\"},\"wordCount\":977,\"articleSection\":[\"Chapitre 09 - Veille du 9 av\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-09-04\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-09-04\\\/\",\"name\":\"04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-05-08T21:04:27+00:00\",\"dateModified\":\"2018-03-18T10:03:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-09-04\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-09-04\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-09-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/","og_locale":"fr_FR","og_type":"article","og_title":"04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat - Pnin\u00e9 Halakha","og_description":"Il est de r\u00e8gle qu\u2019il n\u2019y a point de deuil le Chabbat. Aussi, m\u00eame si le 9 av tombe un Chabbat, le je\u00fbne est repouss\u00e9 au dimanche\u00a0; et ce Chabbat, on mange de la viande, on boit du vin, et l\u2019on peut m\u00eame servir un repas digne de Salomon dans toute sa gloire. De m\u00eame, [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-05-08T21:04:27+00:00","article_modified_time":"2018-03-18T10:03:59+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat","datePublished":"2016-05-08T21:04:27+00:00","dateModified":"2018-03-18T10:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/"},"wordCount":977,"articleSection":["Chapitre 09 - Veille du 9 av"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/","url":"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/","name":"04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-05-08T21:04:27+00:00","dateModified":"2018-03-18T10:03:59+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/05-09-04\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/05-09-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"04. Quand le 9 av tombe \u00e0 l\u2019issue de Chabbat"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/3150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=3150"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/3150\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=3150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=3150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=3150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}