{"id":3838,"date":"2014-04-09T00:04:17","date_gmt":"2014-04-08T21:04:17","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=3838"},"modified":"2018-10-22T10:16:01","modified_gmt":"2018-10-22T07:16:01","slug":"14-09-04","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/","title":{"rendered":"04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse"},"content":{"rendered":"<p>Moins le stade de d\u00e9veloppement du f\u0153tus est avanc\u00e9, plus grande est la possibilit\u00e9 de permettre l\u2019interruption de grossesse. \u00c0 l\u2019inverse, plus le d\u00e9veloppement est avanc\u00e9, plus le degr\u00e9 de vitalit\u00e9 que porte le f\u0153tus est manifeste\u00a0; et, de l\u2019avis m\u00eame des d\u00e9cisionnaires indulgents, on ne pourra autoriser l\u2019interruption que dans des cas graves.<\/p>\n<p>Avant que l\u2019embryon n\u2019ait pass\u00e9 quarante jours complets, ses membres n\u2019ont pas encore commenc\u00e9 \u00e0 se former, et il n\u2019a pas encore le statut de f\u0153tus (<em>\u2018oubar<\/em>). Aussi, quand une femme avorte de son embryon dans les quarante premiers jours, l\u2019enfant m\u00e2le qui lui na\u00eetra par la suite aura \u2013 si elle n\u2019a pas d\u2019enfant plus \u00e2g\u00e9 \u2013 le statut de premier-n\u00e9 (<em>bekhor<\/em>), car la grossesse pr\u00e9c\u00e9dente n\u2019est pas plus consid\u00e9r\u00e9e <em>que de l\u2019eau<\/em> (selon l\u2019expression talmudique, en <em>Yevamot <\/em>69b). Aussi, de l\u2019avis m\u00eame d\u2019une partie des d\u00e9cisionnaires rigoureux, en cas de grande n\u00e9cessit\u00e9, il est permis de recourir \u00e0 l\u2019avortement jusqu\u2019au quaranti\u00e8me jour<sup><a href='#_te01ftn9_5' id='_te01ftnref9_5' class='aup1'>[5]<\/a><\/sup>.<\/p>\n<p>\u00c0 partir du quarante-et-uni\u00e8me jour, puisque les membres du f\u0153tus ont commenc\u00e9 de se former, les d\u00e9cisionnaires rigoureux pensent qu\u2019il est interdit d\u2019avorter, \u00e0 moins qu\u2019un danger pour la vie de la m\u00e8re ne soit peut-\u00eatre \u00e0 craindre. Mais d\u2019autres d\u00e9cisionnaires rigoureux estiment que, dans la mesure o\u00f9, les trois premiers mois, on consid\u00e8re que la grossesse de la femme n\u2019est pas encore visible, on peut, en cas de grande n\u00e9cessit\u00e9, proc\u00e9der \u00e0 l\u2019avortement (<em>Yabia Omer<\/em> IV, <em>Even Ha\u2019ezer<\/em> 1, au nom de plusieurs A\u2019haronim).<\/p>\n<p>Face \u00e0 cela, de l\u2019avis des d\u00e9cisionnaires indulgents\u00a0: puisque l\u2019avortement n\u2019est pas interdit au titre du meurtre, il est permis, en cas de grande n\u00e9cessit\u00e9, d\u2019y proc\u00e9der, m\u00eame apr\u00e8s trois mois. Cependant, plus le f\u0153tus se d\u00e9veloppe, plus le motif de la permission d\u2019avorter doit \u00eatre fort. Aussi est-il recommand\u00e9 d\u2019\u00eatre aussi empress\u00e9 que possible pour effectuer les examens n\u00e9cessaires, afin que, s\u2019il s\u2019av\u00e8re n\u00e9cessaire d\u2019avorter, cela puisse se r\u00e9aliser aussi t\u00f4t que possible (<em>Tsits Eli\u00e9zer <\/em>IX 51, 3\u00a0;<em> \u2018Amoud Hayemani <\/em>32).<\/p>\n<p>Apr\u00e8s que le f\u0153tus a atteint un stade de d\u00e9veloppement tel que, s\u2019il naissait, il pourrait survivre par ses propres forces, il n\u2019est presque plus possible, de l\u2019avis m\u00eame des auteurs indulgents, d\u2019autoriser l\u2019avortement. S\u2019il est certain que, m\u00eame dans le cas o\u00f9 le f\u0153tus naissait de fa\u00e7on naturelle, il ne survivrait pas plus de trente jours, une partie des d\u00e9cisionnaires indulgents sont pr\u00eats, en des cas d\u00e9termin\u00e9s, \u00e0 autoriser l\u2019interruption de grossesse.<\/p>\n<p>Quand la poursuite de la grossesse menace la vie de la m\u00e8re, tous les d\u00e9cisionnaires autorisent l\u2019avortement. M\u00eame si les contractions de la naissance ont commenc\u00e9, on tue le f\u0153tus afin de sauver la m\u00e8re. Mais si la t\u00eate de l\u2019enfant, ou la majorit\u00e9 de son corps, est d\u00e9j\u00e0 sortie, on ne lui porte plus atteinte, car l\u2019enfant est alors consid\u00e9r\u00e9 comme une personne humaine, et l\u2019on ne tue pas une personne pour en sauver une autre (<em>Ohalot <\/em>7, 6)<sup><a href='#_te01ftn9_6' id='_te01ftnref9_6' class='aup1'>[6]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref9_5' id='_te01ftn9_5'>[5]<\/a>. Certes, en mati\u00e8re de profanation du Chabbat, la r\u00e8gle est diff\u00e9rente\u00a0: on profane le Chabbat pour sauver un embryon, m\u00eame de moins de quarante jours. Cette permission est motiv\u00e9e par le fait que l\u2019embryon peut se d\u00e9velopper, jusqu\u2019\u00e0 ce qu\u2019il devienne un homme\u00a0; comme le disent nos sages\u00a0: \u00ab\u00a0Profane, pour lui, un Chabbat, afin qu\u2019il garde de nombreux Chabbats\u00a0\u00bb (<em>Yoma<\/em> 85b\u00a0; <em>Halakhot Guedolot<\/em>, Na\u2019hmanide\u00a0; <em>Pnin\u00e9 Halakha, Lois de Chabbat<\/em>, 27, 3). Mais s\u2019agissant du <em>statut<\/em> de l\u2019embryon de moins de quarante jours, le trait\u00e9 <em>Yevamot<\/em> 69b explique que, lorsque la fille d\u2019un Cohen est enceinte d\u2019un Isra\u00e9lite, elle n\u2019en reste pas moins consid\u00e9r\u00e9e, pour l\u2019instant, comme fille de Cohen, et consomme donc de la <em>t\u00e9rouma <\/em>(nourriture r\u00e9serv\u00e9e aux pr\u00eatres), car l\u2019embryon qu\u2019elle porte est consid\u00e9r\u00e9 \u00ab simplement comme de l\u2019eau\u00a0\u00bb. Apr\u00e8s quarante jours, il a d\u00e9j\u00e0 de l\u2019importance, de sorte que la m\u00e8re ne peut plus consommer de <em>t\u00e9rouma<\/em>.<\/p>\n<p>Dans le m\u00eame sens, il appara\u00eet, en mati\u00e8re de primog\u00e9niture, que l\u2019enfant n\u00e9 apr\u00e8s un avortement survenu dans les quarante premiers jours de la grossesse a le statut d\u2019a\u00een\u00e9, car c\u2019est seulement quand un f\u0153tus s\u2019est d\u00e9velopp\u00e9 de mani\u00e8re normale pendant quarante jours que ses membres commencent \u00e0 se former, de sorte qu\u2019il poss\u00e8de une r\u00e9alit\u00e9 concr\u00e8te. Avant cela, le f\u0153tus est consid\u00e9r\u00e9 comme n\u2019ayant pas de r\u00e9alit\u00e9 concr\u00e8te (<em>Choul\u2019han \u2018Aroukh, Yor\u00e9 D\u00e9\u2019a<\/em> 305, 23). De m\u00eame, les m\u00e9decins savent aujourd\u2019hui que, dans une grossesse normale, avant le quaranti\u00e8me jour, les membres du f\u0153tus n\u2019ont pas encore commenc\u00e9 \u00e0 se former\u00a0; puis, apr\u00e8s quarante-deux jours, ils commencent \u00e0 se former.<\/p>\n<p>Il importe de signaler, en cette mati\u00e8re, que, dans les dispensaires, il est d\u2019usage de\u00a0 calculer le commencement de la grossesse en la faisant remonter aux derni\u00e8res r\u00e8gles\u00a0; cependant, la f\u00e9condation ne commence en r\u00e9alit\u00e9 que quatorze jours apr\u00e8s, \u00e0 tout le moins, et ce n\u2019est qu\u2019\u00e0 partir de la f\u00e9condation, c\u2019est-\u00e0-dire de l\u2019union du spermatozo\u00efde et de l\u2019ovule, que l\u2019on commence \u00e0 compter quarante jours. Quand l\u2019avortement intervient apr\u00e8s le quaranti\u00e8me jour \u00e0 compter de la f\u00e9condation, mais que le f\u0153tus a cess\u00e9 de se d\u00e9velopper avant cela, le principe est le suivant\u00a0: si l\u2019\u00e9tat de d\u00e9veloppement du f\u0153tus \u00e9tait semblable \u00e0 celui d\u2019un f\u0153tus qui n\u2019est pas parvenu au quarante-et-uni\u00e8me jour, le fils qui na\u00eetra par la suite d\u2019une nouvelle grossesse requerra, en tant que premier-n\u00e9, un rachat (<em>pidyon<\/em>). En cas de doute, on proc\u00e9dera au rachat, mais sans prononcer la b\u00e9n\u00e9diction.<\/p>\n<p>En pratique, puisque le f\u0153tus est consid\u00e9r\u00e9, jusqu\u2019au quaranti\u00e8me jour, \u00ab\u00a0comme de l\u2019eau\u00a0\u00bb, ceux qui sont indulgents, et autorisent l\u2019avortement en cas de grande n\u00e9cessit\u00e9, pourront \u00eatre indulgents, m\u00eame si la n\u00e9cessit\u00e9 est moins grande. C\u2019est la position des responsa <em>B\u00e9-ahola Chel Torah<\/em> (I 115), au sujet d\u2019une jeune fille non mari\u00e9e, \u00e0 qui il serait difficile de placer l\u2019enfant pour qu\u2019il soit adopt\u00e9\u00a0: en ce cas, il lui est permis d\u2019avorter jusqu\u2019au quaranti\u00e8me jour. C\u2019est aussi la position des responsa <em>Ben\u00e9 Banim<\/em> 3, 38. Une partie des d\u00e9cisionnaires tendant \u00e0 la rigueur \u2013 tel Rav Chelomo Zalman Auerbach \u2013 seraient eux-m\u00eames indulgents en cas de n\u00e9cessit\u00e9, avant quarante jours\u00a0(<em>Nichmat Avraham, \u2018Hochen Michpat<\/em> 425, 1, 4, au sujet de la maladie de Tay-Sachs). Toutefois, certains d\u00e9cisionnaires sont rigoureux avant quarante jours comme apr\u00e8s, car l\u2019essentiel d\u00e9pend, selon eux, du fait de savoir si ce f\u0153tus peut devenir une personne compl\u00e8te, et si l\u2019on peut transgresser le Chabbat pour le sauver (Rav Unterman\u00a0; le <em>Igrot Moch\u00e9, \u2018Hochen Michpat<\/em> II 69 tend \u00e0 s\u2019accorder avec cette opinion). Cf. ci-apr\u00e8s, \u00a7 11, note 10.<\/p>\n<p>Selon les responsa <em>A\u2019hi\u2019ezer<\/em> (III, fin du chap. 65), les Noachides ne sont pas passibles de mort pour un avortement pratiqu\u00e9 avant quarante jours (ce qui laisse entendre que cela ne leur est pas interdit). Pour un Juif, poursuit l\u2019auteur, cela est rabbiniquement interdit. C\u2019est aussi la position du <em>Srid\u00e9 Ech, \u2018Hochen Michpat<\/em> 162, 22\u00a0; le <em>Torat \u2018Hessed, Even Ha\u2019ezer<\/em> 42, 33 pense de m\u00eame au sujet des Noachides.<\/p>\n<p><a href='#_te01ftnref9_6' id='_te01ftn9_6'>[6]<\/a>. Entre quarante jours et le moment o\u00f9 le f\u0153tus peut survivre par lui-m\u00eame, il n\u2019y a pas, a priori, de stade interm\u00e9diaire, comme l\u2019\u00e9crit le <em>\u2018Havot Ya\u00efr<\/em> 31. Cependant, force est de dire que, de l\u2019avis m\u00eame des d\u00e9cisionnaires indulgents, plus le temps passe, plus il est difficile d\u2019autoriser, car la <em>blessure <\/em>et la <em>destruction <\/em>sont alors plus grandes. Aussi, m\u00eame apr\u00e8s quarante jours, il est n\u00e9cessaire, selon les auteurs indulgents, de h\u00e2ter autant que possible les examens, afin que, en cas de n\u00e9cessit\u00e9, l\u2019avortement soit pratiqu\u00e9 d\u00e8s que possible.<\/p>\n<p>Selon les avis indulgents, m\u00eame apr\u00e8s que le f\u0153tus parvient \u00e0 un stade tel que, s\u2019il naissait, il pourrait survivre par lui-m\u00eame, sa mise \u00e0 mort ne serait pas consid\u00e9r\u00e9e comme un meurtre, mais comme une blessure et une destruction. D\u00e8s lors, on pourrait, en cas de tr\u00e8s grande n\u00e9cessit\u00e9, autoriser sa mise \u00e0 mort. Comme nous le voyons au trait\u00e9 <em>\u2018Arakhin<\/em> 7a, si une m\u00e8re est condamn\u00e9e \u00e0 mort par un tribunal (<em>beit-din<\/em>), on tue le f\u0153tus qu\u2019elle porte, avant de l\u2019ex\u00e9cuter elle-m\u00eame, afin de lui \u00e9viter une situation ignominieuse apr\u00e8s son ex\u00e9cution\u00a0; ce n\u2019est que si les contractions de la naissance ont d\u00e9j\u00e0 commenc\u00e9 que l\u2019on attend, pour ex\u00e9cuter la condamn\u00e9e, qu\u2019elle ait accouch\u00e9. Cependant, en pratique, puisque le f\u0153tus est alors proche d\u2019\u00eatre consid\u00e9r\u00e9 comme une personne vivante, les d\u00e9cisionnaires indulgents eux-m\u00eames n\u2019ont pas l\u2019usage d\u2019autoriser l\u2019avortement apr\u00e8s que le f\u0153tus a atteint le stade de d\u00e9veloppement o\u00f9 il pourrait survivre par lui-m\u00eame. Il ressort \u00e9galement des propos du <em>Tsits Eli\u00e9zer<\/em>, premier des d\u00e9cisionnaires \u00e0 avoir abord\u00e9 le probl\u00e8me, que, depuis la fin du septi\u00e8me mois, il y a lieu d\u2019\u00eatre rigoureux (XIII 102, 5-6). Nous l\u2019avons vu, au d\u00e9but de la note 4, certains auteurs, qui estiment que l\u2019avortement n\u2019est pas interdit au titre du meurtre, interdisent n\u00e9anmoins l\u2019avortement dans les cas o\u00f9 il n\u2019y a pas de danger pour la m\u00e8re (<em>Ch\u00e9vet Hal\u00e9vi<\/em> VII 208). L\u2019opinion des d\u00e9cisionnaires indulgents est similaire, \u00e0 partir du moment o\u00f9 le f\u0153tus peut survivre par lui-m\u00eame. (N\u00e9anmoins, le <em>Tsits Eli\u00e9zer<\/em> IX, p. 239, conclusion 14, \u00e9crit qu\u2019il n\u2019y a de v\u00e9ritable interdit qu\u2019\u00e0 partir du moment o\u00f9 la m\u00e8re se trouve sur le lit d\u2019accouchement\u00a0; il appara\u00eet donc que, dans des cas tr\u00e8s difficiles, comme nous l\u2019avons vu ci-dessus, il est possible, m\u00eame alors, d\u2019\u00eatre indulgent.)<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Moins le stade de d\u00e9veloppement du f\u0153tus est avanc\u00e9, plus grande est la possibilit\u00e9 de permettre l\u2019interruption de grossesse. \u00c0 l\u2019inverse, plus le d\u00e9veloppement est avanc\u00e9, plus le degr\u00e9 de vitalit\u00e9 que porte le f\u0153tus est manifeste\u00a0; et, de l\u2019avis m\u00eame des d\u00e9cisionnaires indulgents, on ne pourra autoriser l\u2019interruption que dans des cas graves. Avant [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[167],"tags":[],"class_list":["post-3838","post","type-post","status-publish","format-standard","hentry","category-14-09"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Moins le stade de d\u00e9veloppement du f\u0153tus est avanc\u00e9, plus grande est la possibilit\u00e9 de permettre l\u2019interruption de grossesse. \u00c0 l\u2019inverse, plus le d\u00e9veloppement est avanc\u00e9, plus le degr\u00e9 de vitalit\u00e9 que porte le f\u0153tus est manifeste\u00a0; et, de l\u2019avis m\u00eame des d\u00e9cisionnaires indulgents, on ne pourra autoriser l\u2019interruption que dans des cas graves. Avant [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-08T21:04:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-22T07:16:01+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/14-09-04\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/14-09-04\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse\",\"datePublished\":\"2014-04-08T21:04:17+00:00\",\"dateModified\":\"2018-10-22T07:16:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/14-09-04\\\/\"},\"wordCount\":1790,\"articleSection\":[\"Chapitre 09 - Interruption de grossesse\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/14-09-04\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/14-09-04\\\/\",\"name\":\"04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2014-04-08T21:04:17+00:00\",\"dateModified\":\"2018-10-22T07:16:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/14-09-04\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/14-09-04\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/14-09-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/","og_locale":"fr_FR","og_type":"article","og_title":"04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse - Pnin\u00e9 Halakha","og_description":"Moins le stade de d\u00e9veloppement du f\u0153tus est avanc\u00e9, plus grande est la possibilit\u00e9 de permettre l\u2019interruption de grossesse. \u00c0 l\u2019inverse, plus le d\u00e9veloppement est avanc\u00e9, plus le degr\u00e9 de vitalit\u00e9 que porte le f\u0153tus est manifeste\u00a0; et, de l\u2019avis m\u00eame des d\u00e9cisionnaires indulgents, on ne pourra autoriser l\u2019interruption que dans des cas graves. Avant [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2014-04-08T21:04:17+00:00","article_modified_time":"2018-10-22T07:16:01+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse","datePublished":"2014-04-08T21:04:17+00:00","dateModified":"2018-10-22T07:16:01+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/"},"wordCount":1790,"articleSection":["Chapitre 09 - Interruption de grossesse"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/","url":"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/","name":"04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2014-04-08T21:04:17+00:00","dateModified":"2018-10-22T07:16:01+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/14-09-04\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/14-09-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"04. Avant quarante jours, et \u00e9tapes suivantes de la grossesse"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/3838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=3838"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/3838\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=3838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=3838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=3838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}