{"id":4544,"date":"2000-12-01T00:15:28","date_gmt":"2000-11-30T22:15:28","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=4544"},"modified":"2021-04-28T12:32:20","modified_gmt":"2021-04-28T09:32:20","slug":"12-01-15","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/","title":{"rendered":"15 &#8211; La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple"},"content":{"rendered":"<p>\u00c0 l\u2019\u00e9poque o\u00f9 existait le Temple, c\u2019\u00e9tait une mitsva que d\u2019y venir, \u00e0 l\u2019occasion des trois f\u00eates, comme il est dit\u00a0: \u00ab\u00a0Trois fois l\u2019an, chaque m\u00e2le para\u00eetra en pr\u00e9sence du Seigneur \u00c9ternel, Dieu d\u2019Isra\u00ebl\u00a0\u00bb (Ex 34, 23). C\u2019est d\u2019apr\u00e8s cette mitsva que les trois f\u00eates ont \u00e9t\u00e9 appel\u00e9es <em>r\u00e9galim<sup><a href='#_te01ftn1_s' id='_te01ftnref1_s' class='aup1'>[s]<\/a><\/sup><\/em>, parce que l\u2019on se rendait \u00e0 pied jusqu\u2019au Temple, ainsi qu\u2019il est dit\u00a0: \u00ab\u00a0Trois fois (<em>chaloch r\u00e9galim<\/em>) l\u2019an, tu feras f\u00eate en mon honneur\u00a0\u00bb (Ex 23, 14). Ceux qui ne pouvaient se rendre, sur leurs deux pieds, de J\u00e9rusalem au mont du Temple, comme les vieillards, les malades et les boiteux, \u00e9taient dispens\u00e9s de la mitsva. Les aveugles, les sourds et les muets, eux aussi, en \u00e9taient dispens\u00e9s, parce que ce n\u2019est pas avec perfection qu\u2019ils pouvaient para\u00eetre. De m\u00eame, celui qui \u00e9tait impur ou incirconcis \u00e9tait dispens\u00e9 de la mitsva (<em>\u2018Haguiga<\/em> 4a-b, Ma\u00efmonide, <em>Hilkhot \u2018haguiga<\/em> 2, 1).<\/p>\n<p>C\u2019est aux hommes, et non aux femmes, que cette mitsva est prescrite, parce qu\u2019elle est conditionn\u00e9e par le temps. Ainsi, les femmes pouvaient, en cas de n\u00e9cessit\u00e9, rester \u00e0 la maison pour s\u2019occuper de leurs petits, des malades et des personnes \u00e2g\u00e9es. Toutefois, quand une femme pouvait se rendre au Temple, et qu\u2019elle le faisait, elle accomplissait en cela une mitsva\u00a0; c\u2019est ainsi qu\u2019en pratique de nombreuses femmes avaient coutume de faire ce p\u00e8lerinage. Quand un enfant \u00e9tait capable d\u2019aller \u00e0 pied, de J\u00e9rusalem au mont du Temple, c\u2019\u00e9tait une mitsva pour son p\u00e8re que de l\u2019y emmener.<\/p>\n<p>Puisque les hommes avaient ordre de se rendre au Temple \u00e0 pied, il \u00e9tait \u00e0 craindre que des ennemis ne vinssent piller leurs biens pendant les jours de f\u00eate. C\u2019est pr\u00e9cis\u00e9ment \u00e0 ce propos que la Torah promet que, gr\u00e2ce au m\u00e9rite qu\u2019auraient les Isra\u00e9lites \u00e0 se relier au site du sanctuaire, ils h\u00e9riteraient du pays sans avoir \u00e0 craindre d\u2019ennemi, comme il est dit\u00a0: \u00ab\u00a0Car Je d\u00e9poss\u00e9derai des peuples devant toi, et J\u2019\u00e9largirai ta fronti\u00e8re\u00a0; et nul homme ne convoitera ta terre, quand tu monteras pour para\u00eetre \u00e0 la face de l\u2019\u00c9ternel ton Dieu, trois fois l\u2019an\u00a0\u00bb (Ex 34, 24).<\/p>\n<p>Trois mitsvot ont \u00e9t\u00e9 prescrites \u00e0 Isra\u00ebl \u00e0 l\u2019occasion de ce p\u00e8lerinage\u00a0(<em>\u2018alia la-r\u00e9guel<\/em>, \u00ab\u00a0mont\u00e9e \u00e0 pied\u00a0\u00bb)\u00a0: le fait de para\u00eetre (<em>r\u00e9\u00efya<\/em>), le sacrifice propre \u00e0 la f\u00eate (<em>\u2018haguiga<\/em>) et la joie (<em>sim\u2019ha<\/em>) (<em>\u2018Haguiga<\/em> 6b). <strong>a)<\/strong> La mitsva de l\u2019apparition (<em>r\u00e9\u00efya<\/em>) consiste dans le fait que <em>la face de l\u2019homme soit vue<\/em> dans la cour du Temple (<em>\u2018azara<\/em>), et que chacun apporte un \u00ab\u00a0holocauste d\u2019apparition\u00a0\u00bb (<em>\u2018olat r\u00e9\u00efya<\/em>). Ce sacrifice est appel\u00e9 <em>\u2018ola<\/em>, (\u00ab\u00a0mont\u00e9e\u00a0\u00bb) parce que toute sa chair \u00e9tait \u00e9lev\u00e9e sur l\u2019autel. Celui qui se serait rendu dans la cour du Temple sans apporter sa <em>\u2018ola<\/em>, non seulement n\u2019aurait pas accompli cette mitsva positive, mais aurait encore enfreint un commandement de ne pas faire, comme il est dit\u00a0: \u00ab\u00a0Ils ne para\u00eetront pas \u00e0 vide devant Moi\u00a0\u00bb (Ex 34, 20). <strong>b)<\/strong> Quand on parle de <em>\u2018haguiga<\/em>, on d\u00e9signe par-l\u00e0 le sacrifice de <em>chelam\u00e9-\u2018haguiga<\/em> (r\u00e9mun\u00e9ratoire de f\u00eate), c\u2019est-\u00e0-dire un sacrifice r\u00e9mun\u00e9ratoire (<em>chelamim<\/em>) dont certaines graisses (<em>\u2018h\u00e9lev<\/em>) \u00e9taient fum\u00e9es sur l\u2019autel, tandis qu\u2019une partie de sa chair \u00e9tait donn\u00e9e aux pr\u00eatres, et que la grande majorit\u00e9 de sa chair \u00e9tait consomm\u00e9e dans la saintet\u00e9 par l\u2019offreur de ce sacrifice, les membres de sa famille et ses invit\u00e9s. <strong>c)<\/strong> La mitsva de la joie consistait \u00e0 ajouter des <em>chelam\u00e9-sim\u2019ha<\/em> (r\u00e9mun\u00e9ratoires de joie) selon les besoins de sa consommation\u00a0; plus les membres de sa famille et ses invit\u00e9s \u00e9taient nombreux, plus nombreux \u00e9taient les <em>chelam\u00e9-sim\u2019ha<\/em> que la mitsva obligeait \u00e0 offrir. Et celui qui, de toute fa\u00e7on, avait l\u2019obligation d\u2019apporter la d\u00eeme de ses b\u00eates, ou de sacrifier des b\u00eates dont il devait faire l\u2019offrande votive ou spontan\u00e9e, accomplissait la mitsva de la joie en les sacrifiant et en en mangeant la chair (Ma\u00efmonide, <em>Hilkhot \u2018haguiga<\/em> 1, 1\u00a0; 2, 8-10).<\/p>\n<p>Ma\u00efmonide \u00e9crit\u00a0:<\/p>\n<p>Quand on immolera le r\u00e9mun\u00e9ratoire de f\u00eate et les r\u00e9mun\u00e9ratoires de joie, on ne se contentera pas de manger avec ses enfants et sa femme, en ayant l\u2019illusion d\u2019accomplir, ce faisant, une mitsva parfaite. On a l\u2019obligation de r\u00e9jouir les pauvres et les malheureux, comme il est dit\u00a0: \u00ab\u00a0\u2026 et le l\u00e9vite, le pros\u00e9lyte, l\u2019orphelin et la veuve\u00a0\u00bb (Dt 16, 14). On leur servira donc \u00e0 manger et \u00e0 boire selon sa fortune. Celui qui aura mang\u00e9 ses sacrifices sans r\u00e9jouir ceux-l\u00e0 avec lui, il est dit de lui\u00a0: \u00ab\u00a0Leurs sacrifices sont pour eux comme un repas de deuil, tous ceux qui le mangent en seront rendus impurs, car leur pain est pour eux seuls\u00a0\u00bb (Os 9,4) La mitsva oblige \u00e0 l\u2019\u00e9gard du l\u00e9vite plus que de tout autre, car il n\u2019a ni part ni h\u00e9ritage, et ne re\u00e7oit pas de pr\u00e9sents sur les viandes\u00a0\u00bb (<em>Hilkhot \u2018haguiga<\/em> 2, 14).<\/p>\n<p>Bien que l\u2019on n\u2019offre point de sacrifices individuels les jours de f\u00eate, on offre l\u2019holocauste d\u2019apparition, le r\u00e9mun\u00e9ratoire de f\u00eate et les r\u00e9mun\u00e9ratoires de joie, car une mitsva explicite commande de les apporter le premier jour. Mais on n\u2019offre pas ces sacrifices le Chabbat. Si l\u2019on a manqu\u00e9 de les apporter au premier jour de f\u00eate, c\u2019est une mitsva que de le faire avant la fin de la f\u00eate\u00a0: \u00e0 Pessa\u2019h, jusqu\u2019au septi\u00e8me jour\u00a0; \u00e0 Soukot, jusqu\u2019\u00e0 la fin de Chemini \u2018ats\u00e9ret\u00a0; \u00e0 Chavou\u2019ot, jusqu\u2019\u00e0 la fin du sixi\u00e8me jour suivant la f\u00eate. Si l\u2019on a manqu\u00e9 de les offrir avant l\u2019expiration de ces jours, on aura manqu\u00e9 d\u2019accomplir sa mitsva (Ma\u00efmonide, ibid. 4-8).<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref1_s' id='_te01ftn1_s'>[s]<\/a>. D\u2019apr\u00e8s <em>r\u00e9guel<\/em>, jambe. Les <em>r\u00e9galim<\/em> sont donc les f\u00eates de p\u00e8lerinage, celles que l\u2019on c\u00e9l\u00e8bre \u00e0 l\u2019issue d\u2019une marche. Mais le mot signifie aussi \u00ab\u00a0fois\u00a0\u00bb, de sorte que <em>chaloch r\u00e9galim<\/em> peut vouloir dire, selon le contexte, <em>trois f\u00eates<\/em>, ou <em>trois fois<\/em>, comme on va le voir imm\u00e9diatement.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l\u2019\u00e9poque o\u00f9 existait le Temple, c\u2019\u00e9tait une mitsva que d\u2019y venir, \u00e0 l\u2019occasion des trois f\u00eates, comme il est dit\u00a0: \u00ab\u00a0Trois fois l\u2019an, chaque m\u00e2le para\u00eetra en pr\u00e9sence du Seigneur \u00c9ternel, Dieu d\u2019Isra\u00ebl\u00a0\u00bb (Ex 34, 23). C\u2019est d\u2019apr\u00e8s cette mitsva que les trois f\u00eates ont \u00e9t\u00e9 appel\u00e9es r\u00e9galim[s], parce que l\u2019on se rendait \u00e0 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[191],"tags":[],"class_list":["post-4544","post","type-post","status-publish","format-standard","hentry","category-12-01"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>15 - La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15 - La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l\u2019\u00e9poque o\u00f9 existait le Temple, c\u2019\u00e9tait une mitsva que d\u2019y venir, \u00e0 l\u2019occasion des trois f\u00eates, comme il est dit\u00a0: \u00ab\u00a0Trois fois l\u2019an, chaque m\u00e2le para\u00eetra en pr\u00e9sence du Seigneur \u00c9ternel, Dieu d\u2019Isra\u00ebl\u00a0\u00bb (Ex 34, 23). C\u2019est d\u2019apr\u00e8s cette mitsva que les trois f\u00eates ont \u00e9t\u00e9 appel\u00e9es r\u00e9galim[s], parce que l\u2019on se rendait \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-11-30T22:15:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-28T09:32:20+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-01-15\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-01-15\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"15 &#8211; La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple\",\"datePublished\":\"2000-11-30T22:15:28+00:00\",\"dateModified\":\"2021-04-28T09:32:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-01-15\\\/\"},\"wordCount\":1088,\"articleSection\":[\"01 - Introduction\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-01-15\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-01-15\\\/\",\"name\":\"15 - La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-11-30T22:15:28+00:00\",\"dateModified\":\"2021-04-28T09:32:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-01-15\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-01-15\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-01-15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"15 &#8211; La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15 - La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/","og_locale":"fr_FR","og_type":"article","og_title":"15 - La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple - Pnin\u00e9 Halakha","og_description":"\u00c0 l\u2019\u00e9poque o\u00f9 existait le Temple, c\u2019\u00e9tait une mitsva que d\u2019y venir, \u00e0 l\u2019occasion des trois f\u00eates, comme il est dit\u00a0: \u00ab\u00a0Trois fois l\u2019an, chaque m\u00e2le para\u00eetra en pr\u00e9sence du Seigneur \u00c9ternel, Dieu d\u2019Isra\u00ebl\u00a0\u00bb (Ex 34, 23). C\u2019est d\u2019apr\u00e8s cette mitsva que les trois f\u00eates ont \u00e9t\u00e9 appel\u00e9es r\u00e9galim[s], parce que l\u2019on se rendait \u00e0 [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-11-30T22:15:28+00:00","article_modified_time":"2021-04-28T09:32:20+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"15 &#8211; La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple","datePublished":"2000-11-30T22:15:28+00:00","dateModified":"2021-04-28T09:32:20+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/"},"wordCount":1088,"articleSection":["01 - Introduction"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/","url":"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/","name":"15 - La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-11-30T22:15:28+00:00","dateModified":"2021-04-28T09:32:20+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/12-01-15\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/12-01-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"15 &#8211; La mitsva du p\u00e8lerinage, \u00e0 l\u2019\u00e9poque du Temple"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=4544"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4544\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=4544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=4544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=4544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}