{"id":4606,"date":"2000-12-04T00:02:47","date_gmt":"2000-12-03T22:02:47","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=4606"},"modified":"2021-05-06T13:45:16","modified_gmt":"2021-05-06T10:45:16","slug":"12-04-02","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/","title":{"rendered":"02 &#8211; Moudre"},"content":{"rendered":"<p>Moudre (<em>to\u2019hen<\/em>) est interdit le Yom tov. M\u00eame pour les besoins de l\u2019alimentation de Yom tov, il est interdit de moudre de la farine, puisque cette <em>m\u00e9lakha<\/em> se fait, g\u00e9n\u00e9ralement, pour les besoins de nombreux jours, et qu\u2019elle s\u2019inscrit donc dans la cat\u00e9gorie de <em>m\u00e9l\u00e9khet \u2018avoda<\/em> (travail servile), interdite le Yom tov.<\/p>\n<p>En revanche, la <em>dikha<\/em>, c\u2019est-\u00e0-dire le fait de broyer des \u00e9pices, est permise le Yom tov, car on a l\u2019habitude de faire cela dans sa cuisine, pour les besoins des mets du jour m\u00eame (<em>Beitsa <\/em>14a)\u00a0; et il n\u2019est pas n\u00e9cessaire d\u2019apporter un changement \u00e0 la proc\u00e9dure habituelle (<em>Choul\u2019han \u2018Aroukh<\/em> 504, 1). Certains disent qu\u2019il est juste de changer l\u00e9g\u00e8rement la mani\u00e8re de broyer, par exemple en penchant quelque peu le pilon, ou en penchant quelque peu l\u2019ustensile dans lequel sont les \u00e9pices\u00a0; car, de cette fa\u00e7on, on se souviendra que c\u2019est Yom tov, et l\u2019on ne broiera point d\u2019\u00e9pices pour des jours suppl\u00e9mentaires (Rama ad loc.).<\/p>\n<p>Toute la permission de broyer des \u00e9pices le Yom tov, donn\u00e9e par les sages, s\u2019entend \u00e0 la condition que le broyage soit fait dans un mortier domestique, dans lequel il est habituel de broyer des \u00e9pices pour les besoins du jour m\u00eame. Mais il est interdit de moudre du poivre ou ce qui y ressemble dans un petit moulin, puisqu\u2019il est habituel d\u2019y broyer des \u00e9pices pour les besoins de jours nombreux (<em>Beitsa<\/em> 23a, <em>Choul\u2019han \u2018Aroukh<\/em> 504, 1).<\/p>\n<p>Il est permis de r\u00e2per des l\u00e9gumes et du fromage \u00e0 l\u2019aide d\u2019une r\u00e2pe, puisque cet instrument est g\u00e9n\u00e9ralement destin\u00e9 au r\u00e2page d\u2019aliments pour les besoins du jour m\u00eame. Mais quand, pour les besoins du Yom tov, on doit r\u00e2per des aliments que parfois l\u2019on r\u00e2pe pour les besoins de nombreux jours, il faut changer quelque peu le mode op\u00e9ratoire, par exemple en retournant la r\u00e2pe, ou, si l\u2019on a l\u2019habitude de r\u00e2per au-dessus d\u2019une assiette, en r\u00e2pant au-dessus d\u2019un plateau<sup><a href='#_te01ftn4_3' id='_te01ftnref4_3' class='aup1'>[3]<\/a><\/sup>.<\/p>\n<p>Bien entendu, tout ce qui est permis le Chabbat l\u2019est aussi le Yom tov\u00a0; par cons\u00e9quent, il est permis d\u2019\u00e9craser des biscuits ou de la matsa\u00a0: puisqu\u2019ils sont faits de farine, ils ont d\u00e9j\u00e0 subi une mouture, de sorte que l\u2019interdit de moudre ne s\u2019applique plus \u00e0 eux. Certes, le Chabbat, les sages ont interdit de les moudre \u00e0 l\u2019aide d\u2019un ustensile sp\u00e9cialement destin\u00e9 \u00e0 effriter, tel qu\u2019une r\u00e2pe\u00a0; cela, afin de ne pas sembler moudre de mani\u00e8re interdite. Mais le Yom tov, il est permis de les effriter, m\u00eame \u00e0 la r\u00e2pe (Rama 504, 3, <em>Les Lois de Chabbat<\/em> I 12, 1-2).<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref4_3' id='_te01ftn4_3'>[3]<\/a>. De prime abord, pour le <em>Choul\u2019han \u2018Aroukh<\/em> 504, 1, il n\u2019est pas n\u00e9cessaire de faire un quelconque changement (comme l\u2019\u00e9crit le <em>Or l\u00e9-Tsion<\/em> III 19, 5)\u00a0; mais pour le Rama 504, 1 et 3, il faut un changement. Cependant, en pratique, lorsqu\u2019on r\u00e2pe, \u00e0 l\u2019aide d\u2019une r\u00e2pe, une chose qu\u2019on a l\u2019habitude de r\u00e2per pour le jour m\u00eame seulement, il appara\u00eet que c\u2019est une chose dont le go\u00fbt s\u2019alt\u00e8re avec le temps, de sorte que le Rama lui-m\u00eame s\u2019accorderait \u00e0 dire, semble-t-il, qu\u2019il est permis de la r\u00e2per sans y mettre de changement (conform\u00e9ment \u00e0 sa propre source, le Rivach 484).<\/p>\n<p>\u00c0 l\u2019inverse, quand il s\u2019agit d\u2019une chose dont le go\u00fbt ne s\u2019alt\u00e8re pas, trois motifs associ\u00e9s justifient que l\u2019on soit rigoureux, et que l\u2019on imprime \u00e0 l\u2019acte un changement, si bien que, du point de vue m\u00eame du <em>Choul\u2019han \u2018Aroukh<\/em>, il conviendrait de se conduire ainsi\u00a0: a) Le <em>Maguen Avraham<\/em> 504, 7 \u00e9crit qu\u2019il est interdit de r\u00e2per, \u00e0 l\u2019aide d\u2019une r\u00e2pe, une chose que l\u2019on a l\u2019habitude de r\u00e2per pour les besoins de nombreux jours, mais que c\u2019est permis si l\u2019on y fait un changement (il se peut que le <em>Choul\u2019han \u2018Aroukh<\/em> serait d\u2019accord avec cela, si l\u2019on en juge d\u2019apr\u00e8s ce qu\u2019il \u00e9crit en 504, 1 au sujet du sel\u00a0; c\u2019est dans un sens proche que s\u2019exprime le <em>\u2018Hazon \u2018Ovadia<\/em> p. 71). b) Comme nous l\u2019avons vu au chap. 3 \u00a7 8, une chose que l\u2019on aurait pu pr\u00e9parer d\u00e8s la veille de Yom tov et que l\u2019on n\u2019a pas pr\u00e9par\u00e9e, il est permis de la pr\u00e9parer pendant Yom tov, \u00e0 la condition de modifier quelque peu la mani\u00e8re. c) Selon les <em>Hagahot ha-S\u00e9fer Mitsvot Qatan<\/em> et le Rama 504, 1, il faut toujours modifier quelque peu la mani\u00e8re, afin de se souvenir que c\u2019est Yom tov, et que l\u2019on n\u2019en vienne pas \u00e0 pr\u00e9parer pour de nombreux jours.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Moudre (to\u2019hen) est interdit le Yom tov. M\u00eame pour les besoins de l\u2019alimentation de Yom tov, il est interdit de moudre de la farine, puisque cette m\u00e9lakha se fait, g\u00e9n\u00e9ralement, pour les besoins de nombreux jours, et qu\u2019elle s\u2019inscrit donc dans la cat\u00e9gorie de m\u00e9l\u00e9khet \u2018avoda (travail servile), interdite le Yom tov. En revanche, la [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[193],"tags":[],"class_list":["post-4606","post","type-post","status-publish","format-standard","hentry","category-12-04"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>02 - Moudre - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"02 - Moudre - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Moudre (to\u2019hen) est interdit le Yom tov. M\u00eame pour les besoins de l\u2019alimentation de Yom tov, il est interdit de moudre de la farine, puisque cette m\u00e9lakha se fait, g\u00e9n\u00e9ralement, pour les besoins de nombreux jours, et qu\u2019elle s\u2019inscrit donc dans la cat\u00e9gorie de m\u00e9l\u00e9khet \u2018avoda (travail servile), interdite le Yom tov. En revanche, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-12-03T22:02:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-06T10:45:16+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-02\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"02 &#8211; Moudre\",\"datePublished\":\"2000-12-03T22:02:47+00:00\",\"dateModified\":\"2021-05-06T10:45:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-02\\\/\"},\"wordCount\":837,\"articleSection\":[\"04 - Travaux relatifs aux aliments\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-02\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-02\\\/\",\"name\":\"02 - Moudre - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-12-03T22:02:47+00:00\",\"dateModified\":\"2021-05-06T10:45:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-02\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-02\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"02 &#8211; Moudre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"02 - Moudre - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/","og_locale":"fr_FR","og_type":"article","og_title":"02 - Moudre - Pnin\u00e9 Halakha","og_description":"Moudre (to\u2019hen) est interdit le Yom tov. M\u00eame pour les besoins de l\u2019alimentation de Yom tov, il est interdit de moudre de la farine, puisque cette m\u00e9lakha se fait, g\u00e9n\u00e9ralement, pour les besoins de nombreux jours, et qu\u2019elle s\u2019inscrit donc dans la cat\u00e9gorie de m\u00e9l\u00e9khet \u2018avoda (travail servile), interdite le Yom tov. En revanche, la [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-12-03T22:02:47+00:00","article_modified_time":"2021-05-06T10:45:16+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"02 &#8211; Moudre","datePublished":"2000-12-03T22:02:47+00:00","dateModified":"2021-05-06T10:45:16+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/"},"wordCount":837,"articleSection":["04 - Travaux relatifs aux aliments"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/","url":"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/","name":"02 - Moudre - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-12-03T22:02:47+00:00","dateModified":"2021-05-06T10:45:16+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/12-04-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"02 &#8211; Moudre"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=4606"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4606\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=4606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=4606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=4606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}