{"id":4612,"date":"2000-12-04T00:05:42","date_gmt":"2000-12-03T22:05:42","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=4612"},"modified":"2021-05-06T13:49:24","modified_gmt":"2021-05-06T10:49:24","slug":"12-04-05","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/","title":{"rendered":"05 &#8211; D\u00e9tail des r\u00e8gles du tri"},"content":{"rendered":"<p>Quand on est en pr\u00e9sence d\u2019un m\u00e9lange de parties que l\u2019on souhaite consommer (<em>okhel<\/em>) et de parties que l\u2019on ne souhaite pas consommer (<em>psolet<\/em>, \u00ab\u00a0d\u00e9chet\u00a0\u00bb), on les s\u00e9parera de la fa\u00e7on que l\u2019on trouve commode, afin de limiter l\u2019effort pendant Yom tov. Si la majorit\u00e9 du m\u00e9lange consiste en <em>okhel<\/em>, on en \u00f4tera le <em>psolet<\/em>. Si la majorit\u00e9 consiste en <em>psolet<\/em>, on en retirera l\u2019<em>okhel<\/em> (<em>Beitsa<\/em> 14b)<sup><a href='#_te01ftn4_7' id='_te01ftnref4_7' class='aup1'>[7]<\/a><\/sup>.<\/p>\n<p>Le Chabbat, certains estiment qu\u2019il est interdit d\u2019\u00e9plucher, \u00e0 l\u2019aide d\u2019un \u00e9pluche-l\u00e9gumes, des fruits ou des l\u00e9gumes dont on pourrait manger la peau (<em>Les Lois de Chabbat<\/em> I 11, 8), tandis que, le Yom tov, il est permis d\u2019\u00e9plucher, \u00e0 l\u2019aide d\u2019un tel ustensile, m\u00eame des fruits ou l\u00e9gumes dont la peau ou l\u2019\u00e9corce n\u2019est pas propre \u00e0 la consommation. Le Chabbat, il est interdit d\u2019extraire les noyaux d\u2019olives \u00e0 l\u2019aide d\u2019un ustensile sp\u00e9cialement con\u00e7u pour cela (ibid. 11, 7)\u00a0; le Yom tov, c\u2019est permis. Le Chabbat, nombreux sont ceux qui interdisent d\u2019\u00f4ter les ar\u00eates de poisson ou les os de la viande avant d\u2019avoir commenc\u00e9 d\u2019en manger (ibid. 11, 9)\u00a0; tandis que, le Yom tov, tout le monde s\u2019accorde \u00e0 dire qu\u2019il est permis d\u2019\u00f4ter ces ar\u00eates ou os avant le repas.<\/p>\n<p>Le Chabbat, il est interdit de verser le liquide qui accompagne le ma\u00efs ou les petits pois en conserve\u00a0; de m\u00eame, il est interdit de verser l\u2019huile qui se trouve dans une bo\u00eete de thon (ibid. 11, 13)\u00a0; le Yom tov, c\u2019est permis. Le Chabbat, il ne faut pas utiliser une \u00e9cumoire pour \u00e9goutter les aliments (ibid.), tandis que c\u2019est permis le Yom tov. Le Chabbat, il est interdit de filtrer l\u2019eau des champignons\u00a0; de m\u00eame, il est interdit de s\u00e9parer la partie liquide d\u2019un bouillon des morceaux d\u2019aliments qui s\u2019y trouvent\u00a0; et il est \u00e9videmment interdit de le faire \u00e0 l\u2019aide d\u2019une passoire (ibid. 11, 12)\u00a0; le Yom tov, c\u2019est permis (<em>Chemirat Chabbat Kehilkhata<\/em> 4, 6).<\/p>\n<p>De m\u00eame que, pour les besoins de Yom tov, il est permis de trier des aliments, de m\u00eame est-il permis de trier des v\u00eatements, des ustensiles ou des jeux (<em>Or l\u00e9-Tsion<\/em> III 19, 7).<\/p>\n<p>Comme nous l\u2019avons vu (ci-dessus, chap. 3\u00a0\u00a7 8), tant qu\u2019il est possible d\u2019accomplir la <em>m\u00e9lakha<\/em> la veille de Yom tov, sans que la nourriture n\u2019en soit alt\u00e9r\u00e9e, il faut l\u2019accomplir la veille de Yom tov. Si on ne l\u2019a pas accomplie la veille, il sera permis de l\u2019accomplir \u00e0 Yom tov m\u00eame, \u00e0 condition d\u2019apporter un changement (<em>chinou\u00ef<\/em>) \u00e0 la mani\u00e8re habituelle. Toutefois, il n\u2019est pas n\u00e9cessaire d\u2019y apporter un grand changement. Si donc on a l\u2019habitude de trier sur une assiette, on triera sur la table ou sur quelque autre semblable support (<em>Cha\u2019ar\u00e9 Tsioun<\/em> 495, 10)<sup><a href='#_te01ftn4_8' id='_te01ftnref4_8' class='aup1'>[8]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref4_7' id='_te01ftn4_7'>[7]<\/a>. Certes, quand la <em>psolet <\/em>est en grande quantit\u00e9, et m\u00eame dans le cas o\u00f9 il serait plus facile de l\u2019extraire, c\u2019est la partie alimentaire qu\u2019il faut extraire d\u2019entre la <em>psolet<\/em> (<em>Choul\u2019han \u2018Aroukh Harav<\/em> 510, 4, <em>Chemirat Chabbat Kehilkhata<\/em> 4, 3). La raison en est que, dans le cas o\u00f9 le \u00ab\u00a0d\u00e9chet\u00a0\u00bb constitue la majorit\u00e9, il n\u2019est pas \u00ab\u00a0annex\u00e9\u00a0\u00bb \u00e0 la partie comestible, de sorte qu\u2019il est consid\u00e9r\u00e9 comme <em>mouqts\u00e9<\/em>\u00a0[objet qu\u2019il est interdit de d\u00e9placer pendant Chabbat] ; aussi est-il interdit de le retirer. En revanche, quand c\u2019est l\u2019<em>okhel<\/em> qui constitue la majorit\u00e9, il est permis d\u2019extraire la <em>psolet<\/em> \u00e0 la main, car alors la <em>psolet<\/em>, minoritaire, est \u00ab\u00a0annex\u00e9e\u00a0\u00bb \u00e0 la partie comestible, majoritaire. Le d\u00e9chet n\u2019a pas alors le statut de <em>mouqts\u00e9<\/em>, et ce n\u2019est qu\u2019apr\u00e8s qu\u2019on l\u2019aura s\u00e9par\u00e9 de la partie alimentaire qu\u2019il deviendra <em>mouqts\u00e9 <\/em>(d\u2019apr\u00e8s <em>Tossephot <\/em>sur <em>Chabbat <\/em>142b, <em>\u2018Hay\u00e9 Adam<\/em> 82, 2). Certains estiment cependant que, m\u00eame lorsque le d\u00e9chet est majoritaire, on pourra, dans le cas o\u00f9 cela est plus facile, laisser dans son ustensile la partie comestible et en extraire la <em>psolet<\/em>, car on cherche toujours \u00e0 limiter l\u2019effort (cf. <em>Qitsour Choul\u2019han \u2018Aroukh<\/em> 98, 7).<\/p>\n<p><a href='#_te01ftnref4_8' id='_te01ftn4_8'>[8]<\/a>. Les sages ont interdit de filtrer la moutarde \u00e0 l\u2019aide de la passoire ordinaire pr\u00e9vue \u00e0 cet effet, m\u00eame quand le but est de la manger pendant Yom tov\u00a0; cela, parce qu\u2019on a l\u2019habitude de filtrer ainsi la moutarde pour les besoins de nombreux jours. De m\u00eame, les sages ont interdit de faire du fromage, c\u2019est-\u00e0-dire de mettre dans du lait une mati\u00e8re ayant pour effet de s\u00e9parer la partie solide de la partie liquide. Quand il y a \u00e0 cela une grande n\u00e9cessit\u00e9 pour un repas de Yom tov, il est permis de filtrer la moutarde ou de faire du fromage, en apportant un changement \u00e0 la mani\u00e8re ordinaire (<em>Chabbat<\/em> 134a, <em>Choul\u2019han \u2018Aroukh<\/em> 510, 3 et 5, <em>Michna Beroura<\/em> 12 et 21).<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quand on est en pr\u00e9sence d\u2019un m\u00e9lange de parties que l\u2019on souhaite consommer (okhel) et de parties que l\u2019on ne souhaite pas consommer (psolet, \u00ab\u00a0d\u00e9chet\u00a0\u00bb), on les s\u00e9parera de la fa\u00e7on que l\u2019on trouve commode, afin de limiter l\u2019effort pendant Yom tov. Si la majorit\u00e9 du m\u00e9lange consiste en okhel, on en \u00f4tera le psolet. [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[193],"tags":[],"class_list":["post-4612","post","type-post","status-publish","format-standard","hentry","category-12-04"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>05 - D\u00e9tail des r\u00e8gles du tri - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"05 - D\u00e9tail des r\u00e8gles du tri - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Quand on est en pr\u00e9sence d\u2019un m\u00e9lange de parties que l\u2019on souhaite consommer (okhel) et de parties que l\u2019on ne souhaite pas consommer (psolet, \u00ab\u00a0d\u00e9chet\u00a0\u00bb), on les s\u00e9parera de la fa\u00e7on que l\u2019on trouve commode, afin de limiter l\u2019effort pendant Yom tov. Si la majorit\u00e9 du m\u00e9lange consiste en okhel, on en \u00f4tera le psolet. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-12-03T22:05:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-06T10:49:24+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-05\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-05\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"05 &#8211; D\u00e9tail des r\u00e8gles du tri\",\"datePublished\":\"2000-12-03T22:05:42+00:00\",\"dateModified\":\"2021-05-06T10:49:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-05\\\/\"},\"wordCount\":842,\"articleSection\":[\"04 - Travaux relatifs aux aliments\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-05\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-05\\\/\",\"name\":\"05 - D\u00e9tail des r\u00e8gles du tri - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-12-03T22:05:42+00:00\",\"dateModified\":\"2021-05-06T10:49:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-05\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/12-04-05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"05 &#8211; D\u00e9tail des r\u00e8gles du tri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"05 - D\u00e9tail des r\u00e8gles du tri - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/","og_locale":"fr_FR","og_type":"article","og_title":"05 - D\u00e9tail des r\u00e8gles du tri - Pnin\u00e9 Halakha","og_description":"Quand on est en pr\u00e9sence d\u2019un m\u00e9lange de parties que l\u2019on souhaite consommer (okhel) et de parties que l\u2019on ne souhaite pas consommer (psolet, \u00ab\u00a0d\u00e9chet\u00a0\u00bb), on les s\u00e9parera de la fa\u00e7on que l\u2019on trouve commode, afin de limiter l\u2019effort pendant Yom tov. Si la majorit\u00e9 du m\u00e9lange consiste en okhel, on en \u00f4tera le psolet. [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-12-03T22:05:42+00:00","article_modified_time":"2021-05-06T10:49:24+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"05 &#8211; D\u00e9tail des r\u00e8gles du tri","datePublished":"2000-12-03T22:05:42+00:00","dateModified":"2021-05-06T10:49:24+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/"},"wordCount":842,"articleSection":["04 - Travaux relatifs aux aliments"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/","url":"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/","name":"05 - D\u00e9tail des r\u00e8gles du tri - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-12-03T22:05:42+00:00","dateModified":"2021-05-06T10:49:24+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/12-04-05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/12-04-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"05 &#8211; D\u00e9tail des r\u00e8gles du tri"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=4612"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4612\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=4612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=4612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=4612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}