{"id":4930,"date":"2001-01-03T00:03:53","date_gmt":"2001-01-02T22:03:53","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=4930"},"modified":"2021-08-15T22:32:03","modified_gmt":"2021-08-15T19:32:03","slug":"13-03-03","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/","title":{"rendered":"03.Obligation de manger, le premier soir de f\u00eate"},"content":{"rendered":"<p>Il existe une grande diff\u00e9rence entre le premier soir et le reste des jours de f\u00eate\u00a0: tout au long de la f\u00eate, ce n\u2019est que si l\u2019on veut manger un repas r\u00e9gulier (<em>s\u00e9\u2019oudat q\u00e9va\u2019<\/em>) que l\u2019on aura l\u2019obligation de le prendre dans la souka\u00a0; tandis que, si l\u2019on veut se contenter d\u2019une collation informelle (<em>akhilat ar\u2019a\u00ef<\/em>), on pourra la prendre en dehors de la souka. Mais le premier soir de Soukot, c\u2019est une obligation que de manger du pain dans la souka. Cette mitsva s\u2019apprend, par <em>gz\u00e9ra chava&lt;\/em &gt;<sup><a id=\"_te01ftnref3_a\" class=\"aup1\" href=\"#_te01ftn3_a\">[a]<\/a><\/sup>, de la f\u00eate de Pessa\u2019h\u00a0: de m\u00eame que, le premier soir de Pessa\u2019h, c\u2019est une obligation que de manger de la matsa, de m\u00eame le premier soir de Soukot sera-t-il obligatoire de manger du pain dans la souka (<em>Souka<\/em> 27a, <em>Choul\u2019han \u2018Aroukh<\/em> 639, 3). De l\u00e0, nous pouvons apprendre l\u2019importance de la premi\u00e8re soir\u00e9e festive, o\u00f9 sont pos\u00e9s les fondements de toute la f\u00eate.<\/em><\/p>\n<p>Afin d\u2019accomplir cette mitsva avec app\u00e9tit, il faut avoir soin, la veille de Soukot, \u00e0 peu pr\u00e8s dans les trois heures qui pr\u00e9c\u00e8dent le coucher du soleil, de ne pas manger d\u2019aliments qui rassasient (<em>Michna Beroura<\/em> 639, 27).<\/p>\n<p>Le temps de la mitsva commence \u00e0 la tomb\u00e9e de la nuit (<em>tset hakokhavim<\/em>). Puisque la mitsva s\u2019apprend de celle consistant \u00e0 manger de la matsa \u00e0 Pessa\u2019h, il faut manger le pain avant le milieu de la nuit (<em>\u2018hatsot<\/em>). A posteriori, si l\u2019on n\u2019a pas eu le temps de manger avant <em>\u2018hatsot<\/em>, on pourra manger jusqu\u2019\u00e0 l\u2019aube (<em>\u2018alot hacha\u2019har<\/em>)<em>\u00a0<\/em>(<em>Michna Beroura<\/em> 25-26\u00a0; <em>Pnin\u00e9 Halakha \u2013 Les Lois de Pessa\u2019h<\/em> 16, 31).<\/p>\n<p>Avant de commencer \u00e0 manger le pain, le premier soir, on formera l\u2019intention d\u2019accomplir, par cette consommation, la mitsva de l\u2019\u00c9ternel, qui nous ordonna de manger dans la souka en souvenir de la sortie d\u2019\u00c9gypte, et en souvenir des nu\u00e9es de gloire que l\u2019\u00c9ternel \u00e9tendit sur nous pour nous prot\u00e9ger du vent d\u00e9sertique et du soleil. A priori, il convient de former cette intention pendant les sept jours de Soukot. Mais a posteriori, m\u00eame le premier soir, tant que l\u2019on est conscient d\u2019accomplir une mitsva en mangeant dans la souka, on est quitte (<em>Michna Beroura<\/em> 625 1\u00a0; cf. ci-dessus, chap. 1 \u00a7 4-5).<\/p>\n<p>On a grand soin, le soir du s\u00e9der de Pessa\u2019h, de s\u2019acquitter de la consommation d\u2019un <em>kaza\u00eft<\/em> de matsa suivant tous les avis\u00a0; le premier soir de Soukot, on met un soin semblable dans la consommation du pain. Par cons\u00e9quent, on doit manger une quantit\u00e9 de pain au moins \u00e9gale au volume de la moiti\u00e9 d\u2019un \u0153uf. Certains, rigoureux, mangent un volume de pain sup\u00e9rieur \u00e0 celui d\u2019un \u0153uf entier, et il est bon d\u2019agir ainsi. Il n\u2019est pas n\u00e9cessaire de compresser de la <em>\u2018hala<\/em> (du pain) pour mesurer le volume d\u2019un \u0153uf\u00a0: il faut \u00e9valuer le volume de la <em>\u2018hala<\/em> telle qu\u2019elle est. On doit manger la mesure prescrite de pain dans la tranquillit\u00e9, et de fa\u00e7on continue. Si l\u2019on s\u2019est interrompu au milieu de sa consommation, au point d\u2019avoir d\u00e9pass\u00e9 la mesure d\u2019<em>akhilat pras&lt;\/em &gt;<sup><a id=\"_te01ftnref3_b\" class=\"aup1\" href=\"#_te01ftn3_b\">[b]<\/a><\/sup> (environ six ou sept minutes), il faudra remanger une nouvelle mesure de pain<sup><a id=\"_te01ftnref3_3\" class=\"aup1\" href=\"#_te01ftn3_3\">[3]<\/a><\/sup>.<\/em><\/p>\n<p>S\u2019il pleut le premier soir, certains disent qu\u2019il n\u2019y a plus de mitsva de manger un <em>kaza\u00eft <\/em>de pain dans la souka, puisque celui qui \u00e9prouve du d\u00e9sagr\u00e9ment (<em>mitsta\u2019er<\/em>) est dispens\u00e9 d\u2019y rester (Rachba, <em>S\u00e9fer Mitsvot Gadol<\/em>). D\u2019autres estiment que, le premier soir, celui-l\u00e0 m\u00eame qui \u00e9prouve du d\u00e9sagr\u00e9ment \u00e0 \u00eatre dans la souka doit y manger un <em>kaza\u00eft<\/em> ; aussi, m\u00eame s\u2019il pleut, on mangera un <em>kaza\u00eft<\/em> de pain dans la souka (Roch et Ran). En pratique, il est juste d\u2019attendre une heure ou deux, car il se peut que la pluie s\u2019arr\u00eatera, de sorte que l\u2019on pourra accomplir la mitsva d\u2019apr\u00e8s tous les avis. Si la pluie continue de tomber, ou bien qu\u2019elle ait cess\u00e9, mais que, parce que le <em>sekhakh<\/em> est imbib\u00e9 d\u2019eau, des gouttes en tombent encore dans une quantit\u00e9 telle qu\u2019y s\u00e9journer causerait du d\u00e9sagr\u00e9ment, on r\u00e9citera le Qidouch dans la souka, on dira la b\u00e9n\u00e9diction <em>Ch\u00e9h\u00e9\u2019h\u00e9yanou <\/em>sur la f\u00eate elle-m\u00eame, et l\u2019on mangera un <em>kaza\u00eft<\/em> de pain pour accomplir la mitsva d\u2019apr\u00e8s les d\u00e9cisionnaires selon qui le <em>mitsta\u2019er<\/em> lui-m\u00eame a l\u2019obligation de manger dans la souka le premier soir. Mais on ne r\u00e9citera pas la b\u00e9n\u00e9diction <em>Leichev ba-souka<\/em>, cela afin de tenir compte de l\u2019opinion selon laquelle, m\u00eame le premier soir, il n\u2019est pas obligatoire \u00e0 celui qui \u00e9prouve de la g\u00eane de manger dans la souka (Rama 639, 5, <em>Michna Beroura<\/em> 35).<\/p>\n<p>Si la pluie cesse avant le milieu de la nuit (<em>\u2018hatsot<\/em>), et que l\u2019on \u00e9prouve encore quelque plaisir \u00e0 manger du pain, on retournera \u00e0 la souka pour y manger du pain, et l\u2019on r\u00e9citera cette fois la b\u00e9n\u00e9diction <em>Leichev ba-souka<\/em>, afin d\u2019accomplir la mitsva de l\u2019avis m\u00eame de ceux qui estiment qu\u2019elle consiste \u00e0 manger sans en \u00e9prouver de g\u00eane.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div><a id=\"_te01ftn3_a\" href=\"#_te01ftnref3_a\">[a]<\/a>. Analogie. L\u2019une des r\u00e8gles herm\u00e9neutiques du Talmud.<\/div>\n<div><\/div>\n<div><a id=\"_te01ftn3_b\" href=\"#_te01ftnref3_b\">[b]<\/a>. \u00ab\u00a0Temps de consommation d\u2019une demi-miche\u00a0\u00bb, cf. <em>Les Lois de Pessa\u2019h<\/em>, chap. 16 \u00a7 25.<\/div>\n<div>\n<p><a id=\"_te01ftn3_3\" href=\"#_te01ftnref3_3\">[3]<\/a>. Au trait\u00e9 <em>Souka<\/em> 27a du Talmud de Babylone, il est dit que les sages ont appris par <em>gz\u00e9ra chava<\/em> que, de m\u00eame que c\u2019est une mitsva que de manger de la matsa le premier soir de Pessa\u2019h, ainsi est-ce une mitsva que de manger du pain le premier soir de Soukot, dans la souka. Cela laisse entendre que le propos est de manger la mesure d\u2019un <em>kaza\u00eft <\/em>au moins. C\u2019est aussi ce qu\u2019explique le Talmud de J\u00e9rusalem (<em>Souka <\/em>2, 7)\u00a0; c\u2019est en ce sens que s\u2019expriment Ma\u00efmonide, le Roch et d\u2019autres Richonim\u00a0; le <em>Choul\u2019han \u2018Aroukh<\/em> 639, 3 tranche de m\u00eame.<\/p>\n<p>&nbsp;<\/p>\n<p>Les d\u00e9cisionnaires sont partag\u00e9s quant \u00e0 la mesure d\u2019un <em>kaza\u00eft<\/em>\u00a0: selon de nombreux Gu\u00e9onim et Richonim, cela correspond \u00e0 la taille d\u2019une olive de notre temps\u00a0; selon Ma\u00efmonide, c\u2019est pr\u00e8s du tiers du volume d\u2019un \u0153uf\u00a0; selon <em>Tossephot<\/em>, environ la moiti\u00e9 du volume d\u2019un \u0153uf. En raison du doute, le <em>Choul\u2019han \u2018Aroukh, Ora\u2019h \u2018Ha\u00efm<\/em> 486, 1 suit l\u2019opinion de <em>Tossephot<\/em>. Certes, de l\u2019avis d\u2019une nette majorit\u00e9 de d\u00e9cisionnaires, on s\u2019acquitte ainsi\u00a0; mais il y a lieu d\u2019\u00eatre rigoureux en mangeant un volume l\u00e9g\u00e8rement sup\u00e9rieur \u00e0 celui d\u2019un \u0153uf, ce pour trois raisons\u00a0: <strong>a)<\/strong> selon le Ran, la mitsva, le premier soir, est de manger davantage que le volume d\u2019un \u0153uf, car ce n\u2019est qu\u2019\u00e0 partir d\u2019une telle mesure qu\u2019il devient obligatoire de manger dans la souka. Le <em>Michna Beroura<\/em> 639, 22 \u00e9crit qu\u2019il est a priori juste d\u2019adopter cette rigueur. <strong>b)<\/strong> Selon le <em>Noda\u2019 Biyehouda<\/em>, la taille des \u0153ufs de nos jours est de moiti\u00e9 moins grande que celle des \u0153ufs de l\u2019\u00e9poque talmudique\u00a0; aussi, celui qui voudrait manger la mesure de \u00ab\u00a0la moiti\u00e9 d\u2019un \u0153uf\u00a0\u00bb devrait manger le volume d\u2019un \u0153uf. S\u2019agissant de mitsvot de rang toranique, les Ashk\u00e9nazes ont l\u2019habitude d\u2019\u00eatre rigoureux, conform\u00e9ment au <em>Noda\u2019 Biyehouda<\/em>. <strong>c)<\/strong> Bien que les S\u00e9farades n\u2019aient pas coutume de tenir compte de l\u2019opinion du <em>Noda\u2019 Biyehouda<\/em>, beaucoup ont un autre usage rigoureux\u00a0: celui de calculer le volume d\u2019un demi-\u0153uf en fonction du poids de l\u2019eau \u00a0[en d\u2019autres termes, la mesure de pain que l\u2019on doit consommer \u00e9quivaut, en poids, au poids d\u2019un volume d\u2019eau identique au volume d\u2019un demi-\u0153uf]\u00a0; il ressort de cela que le volume de pain (dont le poids \u00e9gale celui du volume d\u2019un demi-\u0153uf en eau) sera sup\u00e9rieure au volume d\u2019un \u0153uf. Certains expliquent que le fondement de ce syst\u00e8me tient au fait que, selon les tenants de ce syst\u00e8me, il ne faut pas calculer le volume de pain tel que celui-ci nous appara\u00eet\u00a0: il faut le compresser (cf. <em>Pnin\u00e9 Halakha \u2013 Lois des b\u00e9n\u00e9dictions<\/em> 10, 5-6\u00a0; <em>Les Lois de Pessa\u2019h<\/em> 16, 22-23).<\/p>\n<p>&nbsp;<\/p>\n<p>Nous voyons donc que, de trois points de vue, il est bon, a priori, de manger une quantit\u00e9 de pain faisant un peu plus du volume d\u2019un \u0153uf, ce qui fait environ la taille d\u2019une tranche ordinaire. Et quiconque le mange tranquillement et sans interruption accomplit \u00e9videmment cette consommation dans le temps dit d\u2019<em>akhilat pras <\/em>(<em>Pnin\u00e9 Halakha \u2013 Lois des b\u00e9n\u00e9dictions<\/em> 10, 7).<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il existe une grande diff\u00e9rence entre le premier soir et le reste des jours de f\u00eate\u00a0: tout au long de la f\u00eate, ce n\u2019est que si l\u2019on veut manger un repas r\u00e9gulier (s\u00e9\u2019oudat q\u00e9va\u2019) que l\u2019on aura l\u2019obligation de le prendre dans la souka\u00a0; tandis que, si l\u2019on veut se contenter d\u2019une collation informelle (akhilat [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[214],"tags":[],"class_list":["post-4930","post","type-post","status-publish","format-standard","hentry","category-13-03"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>03.Obligation de manger, le premier soir de f\u00eate - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"03.Obligation de manger, le premier soir de f\u00eate - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Il existe une grande diff\u00e9rence entre le premier soir et le reste des jours de f\u00eate\u00a0: tout au long de la f\u00eate, ce n\u2019est que si l\u2019on veut manger un repas r\u00e9gulier (s\u00e9\u2019oudat q\u00e9va\u2019) que l\u2019on aura l\u2019obligation de le prendre dans la souka\u00a0; tandis que, si l\u2019on veut se contenter d\u2019une collation informelle (akhilat [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2001-01-02T22:03:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-15T19:32:03+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-03\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-03\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"03.Obligation de manger, le premier soir de f\u00eate\",\"datePublished\":\"2001-01-02T22:03:53+00:00\",\"dateModified\":\"2021-08-15T19:32:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-03\\\/\"},\"wordCount\":1517,\"articleSection\":[\"Chapitre 3 - R\u00e9sider sous la souka\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-03\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-03\\\/\",\"name\":\"03.Obligation de manger, le premier soir de f\u00eate - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2001-01-02T22:03:53+00:00\",\"dateModified\":\"2021-08-15T19:32:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-03\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-03\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-03\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"03.Obligation de manger, le premier soir de f\u00eate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"03.Obligation de manger, le premier soir de f\u00eate - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/","og_locale":"fr_FR","og_type":"article","og_title":"03.Obligation de manger, le premier soir de f\u00eate - Pnin\u00e9 Halakha","og_description":"Il existe une grande diff\u00e9rence entre le premier soir et le reste des jours de f\u00eate\u00a0: tout au long de la f\u00eate, ce n\u2019est que si l\u2019on veut manger un repas r\u00e9gulier (s\u00e9\u2019oudat q\u00e9va\u2019) que l\u2019on aura l\u2019obligation de le prendre dans la souka\u00a0; tandis que, si l\u2019on veut se contenter d\u2019une collation informelle (akhilat [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2001-01-02T22:03:53+00:00","article_modified_time":"2021-08-15T19:32:03+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"03.Obligation de manger, le premier soir de f\u00eate","datePublished":"2001-01-02T22:03:53+00:00","dateModified":"2021-08-15T19:32:03+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/"},"wordCount":1517,"articleSection":["Chapitre 3 - R\u00e9sider sous la souka"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/","url":"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/","name":"03.Obligation de manger, le premier soir de f\u00eate - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2001-01-02T22:03:53+00:00","dateModified":"2021-08-15T19:32:03+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/13-03-03\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-03\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"03.Obligation de manger, le premier soir de f\u00eate"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=4930"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4930\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=4930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=4930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=4930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}