{"id":4941,"date":"2001-01-03T00:05:22","date_gmt":"2001-01-02T22:05:22","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=4941"},"modified":"2021-08-16T23:31:22","modified_gmt":"2021-08-16T20:31:22","slug":"13-03-05","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/","title":{"rendered":"05.B\u00e9n\u00e9diction <em>Leichev ba-souka<\/em>"},"content":{"rendered":"<p>Nos sages ont institu\u00e9 une b\u00e9n\u00e9diction, qui doit \u00eatre r\u00e9cit\u00e9e avant d\u2019accomplir la mitsva de s\u2019installer dans la souka\u00a0: <em>Baroukh Ata Ado-na\u00ef, Elo-h\u00e9nou, M\u00e9lekh ha\u2019olam, acher qidechanou bemitsvotav, v\u00e9tsivanou leichev ba-souka <\/em>(\u00ab\u00a0B\u00e9ni sois-Tu, \u00c9ternel, notre Dieu, Roi de l\u2019univers, qui nous as sanctifi\u00e9s par tes commandements et nous as ordonn\u00e9 de r\u00e9sider<sup><a id=\"_te01ftnref3_c\" class=\"aup1\" href=\"#_te01ftn3_c\">[c]<\/a><\/sup> dans la souka\u00a0\u00bb). Les coutumes divergent quant au moment de r\u00e9citer cette b\u00e9n\u00e9diction.<\/p>\n<p>Selon de nombreux Richonim \u2013 et telle est l\u2019opinion du Rif et de Ma\u00efmonide \u2013, chaque fois qu\u2019un homme entre dans la souka dans le but d\u2019y rester quelques temps, il r\u00e9citera la b\u00e9n\u00e9diction avant de s\u2019asseoir, m\u00eame s\u2019il n\u2019a pas d\u2019autre intention que d\u2019y \u00eatre assis sans rien faire, puisqu\u2019il accomplit par ce seul fait une mitsva. Telle est en \u00a0pratique la coutume des <strong>originaires du Y\u00e9men<\/strong>\u00a0: tout de suite apr\u00e8s \u00eatre entr\u00e9 dans la souka, ils r\u00e9citent la b\u00e9n\u00e9diction debout, puis s\u2019assoient.<\/p>\n<p>Mais la coutume des autres communaut\u00e9s suit l\u2019opinion de Rabb\u00e9nou Tam, d\u2019apr\u00e8s qui la b\u00e9n\u00e9diction se r\u00e9cite \u00e0 l\u2019occasion d\u2019une consommation alimentaire, car celle-ci est plus fondamentale\u00a0; et, par la b\u00e9n\u00e9diction r\u00e9cit\u00e9e avant de manger, on s\u2019acquitte pour toutes les autres choses que l\u2019on fait dans le cadre de la mitsva d\u2019habiter la souka. Et bien que le sommeil soit, lui aussi, important, il est \u00e0 craindre que l\u2019on r\u00e9cite la b\u00e9n\u00e9diction avant de se coucher, et que, finalement, on ne s\u2019endorme pas\u00a0; tandis que le fait de manger d\u00e9pend de la d\u00e9cision de l\u2019homme, si bien que c\u2019est sur cela qu\u2019il convient de prononcer la b\u00e9n\u00e9diction. La question qui se pose est\u00a0: sur quel type d\u2019aliment doit-on dire la b\u00e9n\u00e9diction\u00a0?<\/p>\n<p><strong>Suivant la coutume ashk\u00e9naze<\/strong>, si l\u2019on s\u2019appr\u00eate \u00e0 consommer une quantit\u00e9 telle que l\u2019on a l\u2019obligation de manger dans la souka, on dira la b\u00e9n\u00e9diction <em>Leichev ba-souka<\/em> sur une telle consommation. Par cons\u00e9quent, si l\u2019on a l\u2019intention de manger du pain ou des aliments <em>m\u00e9zonot<\/em> dans une quantit\u00e9 sup\u00e9rieure au volume de <em>kabeitsa<\/em> (volume d\u2019un \u0153uf), on r\u00e9citera, avec la b\u00e9n\u00e9diction de l\u2019aliment lui-m\u00eame, la b\u00e9n\u00e9diction <em>Leichev ba-souka<\/em>. Et si l\u2019on n\u2019a pas l\u2019intention de manger cette quantit\u00e9 \u00e0 l\u2019occasion de son pr\u00e9sent s\u00e9jour sous la souka, on dira cette b\u00e9n\u00e9diction, m\u00eame pour une quelconque quantit\u00e9 de <em>m\u00e9zonot<\/em>, de vin, ou de quelque autre aliment important que l\u2019on go\u00fbte. Et bien qu\u2019il y ait en cette mati\u00e8re d\u2019autres coutumes, c\u2019est ainsi qu\u2019il convient d\u2019agir.<\/p>\n<p><strong>Selon la coutume s\u00e9farade<\/strong>, on dit <em>Leichev ba-souka<\/em> pour une consommation importante, sur laquelle on a l\u2019habitude de \u00ab\u00a0fixer\u00a0\u00bb son repas. Il faut, \u00e0 cet \u00e9gard, distinguer entre le pain et les autres aliments \u00e0 base de c\u00e9r\u00e9ales. S\u2019il s\u2019agit de pain, dans le cas m\u00eame o\u00f9 l\u2019on ne doit manger qu\u2019un peu plus d\u2019un volume de <em>kabeitsa<\/em>, on dira <em>Leichev ba-souka<\/em>. Pour les autres aliments \u00e0 base de c\u00e9r\u00e9ales, qu\u2019il s\u2019agisse de g\u00e2teaux ou de mets cuits \u00e0 l\u2019eau \u2013 tels que les p\u00e2tes, les langues d\u2019oiseau ou la bouillie \u2013, on ne dira la b\u00e9n\u00e9diction <em>Leichev ba-souka<\/em> que si l\u2019on en mange une quantit\u00e9 dont on puisse se rassasier lors d\u2019un repas habituel, c\u2019est-\u00e0-dire un volume \u00e9quivalent \u00e0 quatre \u0153ufs<sup><a id=\"_te01ftnref3_6\" class=\"aup1\" href=\"#_te01ftn3_6\">[6]<\/a><\/sup>.<\/p>\n<p>Il semble que, de nos jours, d\u2019apr\u00e8s la coutume s\u00e9farade elle-m\u00eame, celui-l\u00e0 m\u00eame qui prend un v\u00e9ritable <strong>repas sans pain ni aliments <em>m\u00e9zonot<\/em><\/strong> devra dire la b\u00e9n\u00e9diction \u2013 par exemple si l\u2019on mange de la soupe, de la viande, du riz et des pommes de terre. Certes, autrefois, la consigne \u00e9tait de ne pas r\u00e9citer la b\u00e9n\u00e9diction pour un repas d\u00e9pourvu de pain\u00a0; mais de nos jours, o\u00f9 il est habituel de prendre un repas complet et important sans aliment \u00e0 base de c\u00e9r\u00e9ales, un tel repas doit \u00eatre consid\u00e9r\u00e9 comme une <em>s\u00e9\u2019oudat q\u00e9va\u2019<\/em> (repas \u00ab\u00a0r\u00e9gulier\u00a0\u00bb), pour laquelle la b\u00e9n\u00e9diction est requise. Cependant, si l\u2019on sait que ses parents ont soin de ne pas la r\u00e9citer \u00e0 l\u2019occasion de tels repas, on est autoris\u00e9 \u00e0 perp\u00e9tuer leur coutume. Mais pour sortir du doute, il est pr\u00e9f\u00e9rable de veiller \u00e0 prendre du pain \u00e0 l\u2019occasion de ces repas, de fa\u00e7on \u00e0 r\u00e9citer la b\u00e9n\u00e9diction <em>Leichev ba-souka&lt;\/em &gt;<sup><a id=\"_te01ftnref3_7\" class=\"aup1\" href=\"#_te01ftn3_7\">[7]<\/a><\/sup>.<\/em><\/p>\n<div>\n<hr size=\"1\" \/>\n<div><a id=\"_te01ftn3_c\" href=\"#_te01ftnref3_c\">[c]<\/a>. Litt\u00e9ralement\u00a0: <em>de nous asseoir<\/em>.&nbsp;<\/p>\n<p><a id=\"_te01ftn3_6\" href=\"#_te01ftnref3_6\">[6]<\/a>. Selon la majorit\u00e9 des Richonim, parmi lesquels le <em>Halakhot Guedolot<\/em>, le Rav Ha\u00ef Gaon, le Rif, Ma\u00efmonide et Rachi, d\u00e8s lors que l\u2019on entre dans la souka au titre de la mitsva, m\u00eame si l\u2019on a seulement l\u2019intention de s\u2019y asseoir, on r\u00e9cite la b\u00e9n\u00e9diction. Telle est la coutume y\u00e9m\u00e9nite, et telle est en pratique l\u2019opinion du Gaon de Vilna. Face \u00e0 cela, Rabb\u00e9nou Tam, le <em>\u2018Itour<\/em>, Rav Yehouda\u00ef Gaon et d\u2019autres Gu\u00e9onim estiment que l\u2019on dit la b\u00e9n\u00e9diction <em>quand on se restaure<\/em> dans la souka\u00a0; telle est la coutume de la majorit\u00e9 des communaut\u00e9s juives (<em>Choul\u2019han \u2018Aroukh<\/em> 639, 8, <em>Michna Beroura<\/em>). Les A\u2019haronim sont partag\u00e9s quant aux conditions dans lesquelles se r\u00e9cite la b\u00e9n\u00e9diction. Selon certains auteurs, pour tout aliment qu\u2019il est obligatoire de consommer dans la souka, on r\u00e9cite la b\u00e9n\u00e9diction <em>Leichev ba-souka<\/em>. C\u2019est ce qu\u2019\u00e9crit le <em>Guinat Vradim<\/em>, et telle est la coutume ashk\u00e9naze (<em>Michna Beroura<\/em> 639, 16 et 46). Selon la coutume s\u00e9farade, on dit la b\u00e9n\u00e9diction sur un repas r\u00e9gulier (<em>s\u00e9\u2019oudat q\u00e9va\u2019<\/em>), comme nous l\u2019expliquerons \u00e0 la prochaine note.<\/p>\n<p>&nbsp;<\/p>\n<p>Selon le <em>Tour\u00e9 Zahav<\/em>, le <em>\u2018Hay\u00e9 Adam<\/em>, le <em>Michna Beroura<\/em> 639, 48 et le <em>\u2018Hazon Ich<\/em>, toute la coutume consistant \u00e0 r\u00e9citer la b\u00e9n\u00e9diction \u00e0 l\u2019occasion d\u2019une prise de nourriture vaut pour autant que l\u2019on a l\u2019intention de manger\u00a0; mais si l\u2019on entre dans la souka pour s\u2019y asseoir, et que l\u2019on sache que, tout le temps de son pr\u00e9sent s\u00e9jour, on n\u2019y mangera pas, on dira la b\u00e9n\u00e9diction sur le fait m\u00eame d\u2019y s\u00e9journer. Selon le <em>Maamar Mordekha\u00ef<\/em> 8, on ne r\u00e9cite la b\u00e9n\u00e9diction que si l\u2019on s\u2019appr\u00eate \u00e0 consommer quelque aliment qu\u2019il est obligatoire de consommer dans la souka. De nombreux Ashk\u00e9nazes ont pour coutume, dans le cas o\u00f9 ils n\u2019auraient pas l\u2019intention de manger une quantit\u00e9 rendant obligatoire le fait d\u2019\u00eatre dans la souka, de r\u00e9citer la b\u00e9n\u00e9diction, m\u00eame pour la consommation d\u2019une quantit\u00e9 minime de <em>m\u00e9zonot<\/em>, de vin, ou d\u2019un autre aliment important. En effet, la position halakhique principale est celle des d\u00e9cisionnaires estimant qu\u2019il y a lieu de r\u00e9citer la b\u00e9n\u00e9diction pour le fait m\u00eame de s\u00e9journer sous la souka. Simplement, puisque la coutume veut que l\u2019on dise la b\u00e9n\u00e9diction <em>\u00e0 l\u2019occasion<\/em> d\u2019une prise de nourriture, on go\u00fbte quelque aliment, et la b\u00e9n\u00e9diction dite sur cette petite consommation vaut aussi, par la m\u00eame occasion, pour le fait d\u2019\u00eatre dans la souka. Cf. <em>Har\u2019havot<\/em> 5, 9-10.<\/p>\n<p>&nbsp;<\/p>\n<p><a id=\"_te01ftn3_7\" href=\"#_te01ftnref3_7\">[7]<\/a>. Cf. ci-dessus, note 5, o\u00f9 il est dit que, si l\u2019on <em>fixe<\/em> son repas sur des aliments carn\u00e9s ou sur du fromage et des garnitures, on a l\u2019obligation de manger dans la souka. Certes, selon le <em>Ye\u2019hav\u00e9 Da\u2019at<\/em> I 65, il ne faut pas r\u00e9citer la b\u00e9n\u00e9diction en ce cas, puisque la coutume s\u00e9farade consiste \u00e0 ne la r\u00e9citer que si l\u2019on prend un repas accompagn\u00e9 de pain, ou de <em>m\u00e9zonot<\/em> dans la quantit\u00e9 correspondant \u00e0 un repas r\u00e9gulier (<em>Choel V\u00e9nichal<\/em> III 95 et 165, <em>\u2018Hazon \u2018Ovadia<\/em> p. 136). Pour le <em>Ben Ich \u2018Ha\u00ef<\/em>, il n\u2019est de coutume de r\u00e9citer la b\u00e9n\u00e9diction que sur un repas accompagn\u00e9 de pain.<\/p>\n<p>&nbsp;<\/p>\n<p>Cependant, il semble que toutes ces paroles valent pour les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes, o\u00f9 l\u2019on ne prenait pas de repas \u00ab r\u00e9gulier\u00a0\u00bb qui ne f\u00fbt accompagn\u00e9 de pain ou, \u00e0 tout le moins, dont la partie principale ne consist\u00e2t en aliments <em>m\u00e9zonot<\/em>. Mais de nos jours, o\u00f9 de tr\u00e8s nombreuses personnes fixent leur repas sur de tels aliments, il s\u2019agit manifestement d\u2019un repas important, pour lequel la b\u00e9n\u00e9diction est requise. Il faut joindre \u00e0 cela l\u2019opinion de la majorit\u00e9 des Richonim, qui pensent que l\u2019on doit dire la b\u00e9n\u00e9diction pour tout s\u00e9jour dans la souka\u00a0; et joindre encore l\u2019opinion (cit\u00e9e dans la note pr\u00e9c\u00e9dente) d\u2019apr\u00e8s laquelle, si l\u2019on n\u2019a pas l\u2019intention de prendre un repas, on r\u00e9citera la b\u00e9n\u00e9diction sur le fait m\u00eame de s\u00e9journer dans la souka. C\u2019est ce qu\u2019\u00e9crit l\u2019auteur des responsa <em>Dvar \u2018Hevron, Ora\u2019h \u2018Ha\u00efm<\/em> 586.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nos sages ont institu\u00e9 une b\u00e9n\u00e9diction, qui doit \u00eatre r\u00e9cit\u00e9e avant d\u2019accomplir la mitsva de s\u2019installer dans la souka\u00a0: Baroukh Ata Ado-na\u00ef, Elo-h\u00e9nou, M\u00e9lekh ha\u2019olam, acher qidechanou bemitsvotav, v\u00e9tsivanou leichev ba-souka (\u00ab\u00a0B\u00e9ni sois-Tu, \u00c9ternel, notre Dieu, Roi de l\u2019univers, qui nous as sanctifi\u00e9s par tes commandements et nous as ordonn\u00e9 de r\u00e9sider[c] dans la souka\u00a0\u00bb). [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[214],"tags":[],"class_list":["post-4941","post","type-post","status-publish","format-standard","hentry","category-13-03"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>05.B\u00e9n\u00e9diction Leichev ba-souka - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"05.B\u00e9n\u00e9diction Leichev ba-souka - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Nos sages ont institu\u00e9 une b\u00e9n\u00e9diction, qui doit \u00eatre r\u00e9cit\u00e9e avant d\u2019accomplir la mitsva de s\u2019installer dans la souka\u00a0: Baroukh Ata Ado-na\u00ef, Elo-h\u00e9nou, M\u00e9lekh ha\u2019olam, acher qidechanou bemitsvotav, v\u00e9tsivanou leichev ba-souka (\u00ab\u00a0B\u00e9ni sois-Tu, \u00c9ternel, notre Dieu, Roi de l\u2019univers, qui nous as sanctifi\u00e9s par tes commandements et nous as ordonn\u00e9 de r\u00e9sider[c] dans la souka\u00a0\u00bb). [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2001-01-02T22:05:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-16T20:31:22+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-05\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-05\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"05.B\u00e9n\u00e9diction Leichev ba-souka\",\"datePublished\":\"2001-01-02T22:05:22+00:00\",\"dateModified\":\"2021-08-16T20:31:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-05\\\/\"},\"wordCount\":1600,\"articleSection\":[\"Chapitre 3 - R\u00e9sider sous la souka\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-05\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-05\\\/\",\"name\":\"05.B\u00e9n\u00e9diction Leichev ba-souka - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2001-01-02T22:05:22+00:00\",\"dateModified\":\"2021-08-16T20:31:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-05\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-03-05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"05.B\u00e9n\u00e9diction Leichev ba-souka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"05.B\u00e9n\u00e9diction Leichev ba-souka - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/","og_locale":"fr_FR","og_type":"article","og_title":"05.B\u00e9n\u00e9diction Leichev ba-souka - Pnin\u00e9 Halakha","og_description":"Nos sages ont institu\u00e9 une b\u00e9n\u00e9diction, qui doit \u00eatre r\u00e9cit\u00e9e avant d\u2019accomplir la mitsva de s\u2019installer dans la souka\u00a0: Baroukh Ata Ado-na\u00ef, Elo-h\u00e9nou, M\u00e9lekh ha\u2019olam, acher qidechanou bemitsvotav, v\u00e9tsivanou leichev ba-souka (\u00ab\u00a0B\u00e9ni sois-Tu, \u00c9ternel, notre Dieu, Roi de l\u2019univers, qui nous as sanctifi\u00e9s par tes commandements et nous as ordonn\u00e9 de r\u00e9sider[c] dans la souka\u00a0\u00bb). [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2001-01-02T22:05:22+00:00","article_modified_time":"2021-08-16T20:31:22+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"05.B\u00e9n\u00e9diction Leichev ba-souka","datePublished":"2001-01-02T22:05:22+00:00","dateModified":"2021-08-16T20:31:22+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/"},"wordCount":1600,"articleSection":["Chapitre 3 - R\u00e9sider sous la souka"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/","url":"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/","name":"05.B\u00e9n\u00e9diction Leichev ba-souka - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2001-01-02T22:05:22+00:00","dateModified":"2021-08-16T20:31:22+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/13-03-05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/13-03-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"05.B\u00e9n\u00e9diction Leichev ba-souka"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=4941"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4941\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=4941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=4941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=4941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}