{"id":4965,"date":"2001-01-04T00:01:02","date_gmt":"2001-01-03T22:01:02","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=4965"},"modified":"2021-08-22T21:04:04","modified_gmt":"2021-08-22T18:04:04","slug":"13-04-01","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/","title":{"rendered":"01.La mitsva des quatre esp\u00e8ces"},"content":{"rendered":"<p>C\u2019est une mitsva que de prendre, pendant la f\u00eate de Soukot, quatre esp\u00e8ces v\u00e9g\u00e9tales\u00a0(<em>arba\u2019a minim<\/em>) : le c\u00e9drat, la branche de palmier, le myrte et le saule, ainsi qu\u2019il est dit\u00a0: \u00ab\u00a0Et vous prendrez, le premier jour, le fruit de l\u2019arbre de splendeur, des palmes de dattier, des rameaux de l\u2019arbre feuillu et des saules de ruisseau\u00a0; et vous vous r\u00e9jouirez devant l\u2019\u00c9ternel votre Dieu, sept jours durant\u00a0\u00bb (Lv 23, 40). Le \u00ab\u00a0fruit de l\u2019arbre de splendeur\u00a0\u00bb (<em>peri \u2018ets hadar<\/em>) est le c\u00e9drat (<em>\u00e9trog<\/em>)\u00a0; les palmes de dattier (<em>kapot temarim<\/em>) sont la branche de palmier (<em>loulav<\/em>)\u00a0; les rameaux de l\u2019arbre feuillu (<em>\u2018anaf \u2018ets \u2018avot<\/em>) sont le myrte (<em>hadas<\/em>)\u00a0; les saules de ruisseau (<em>\u2018arv\u00e9 na\u2019hal<\/em>) sont les branches de saule (<em>\u2018arava<\/em>) (<em>Souka<\/em> 35a\u00a0; cf. M\u00e9\u00efri et Ritva ad loc., et Ma\u00efmonide dans son <em>Introduction \u00e0 la Michna<\/em>).<\/p>\n<p>Puisque le <em>loulav <\/em>est la plus grande des quatre esp\u00e8ces, la mitsva est appel\u00e9e par son nom\u00a0: on parle de prise (ou d\u2019\u00e9l\u00e9vation) du <em>loulav<\/em> (<em>n\u00e9tilat loulav<\/em>). Et c\u2019est en ces termes que nous r\u00e9citons la b\u00e9n\u00e9diction\u00a0: \u00ab\u00a0B\u00e9ni sois-Tu\u2026 qui nous as sanctifi\u00e9s par tes commandements et nous a ordonn\u00e9 de soulever le <em>loulav<\/em>\u00a0\u00bb (<em>Baroukh\u2026 acher qidechanou b\u00e9-mitsvotav, v\u00e9tsivanou \u2018al n\u00e9tilat loulav<\/em>).<\/p>\n<p>Si l\u2019on s\u2019en tient \u00e0 l\u2019obligation toranique, la mitsva consiste seulement \u00e0 prendre le <em>loulav<\/em> le premier jour de Soukot, comme il est dit\u00a0: \u00ab\u00a0Et vous prendrez, le premier jour\u2026\u00a0\u00bb (r\u00e9f. cit.). Ce n\u2019est que sur le site du Temple qu\u2019il nous a \u00e9t\u00e9 prescrit de saisir le <em>loulav <\/em>durant les sept jours de la f\u00eate, comme il est dit, dans la suite du verset\u00a0: \u00ab\u00a0et vous vous r\u00e9jouirez <em>devant l\u2019\u00c9ternel<\/em> votre Dieu, sept jours durant\u00a0\u00bb (ibid.). En pratique, puisqu\u2019il existe une mitsva de se rendre en p\u00e8lerinage \u00e0 J\u00e9rusalem lors des trois f\u00eates, nombreux \u00e9taient les Isra\u00e9lites qui, \u00e0 l\u2019\u00e9poque du Temple, accomplissaient ladite mitsva pendant l\u2019ensemble des sept jours.<\/p>\n<p>Apr\u00e8s la destruction du Temple, Rabban Yo\u2019hanan ben Zaka\u00ef d\u00e9cr\u00e9ta qu\u2019en tout lieu on prendrait le <em>loulav<\/em> sept jours durant, en souvenir du Temple. Il est grandement n\u00e9cessaire de comm\u00e9morer le Temple, car, enseignent les sages, gr\u00e2ce au souvenir du Temple et \u00e0 la perp\u00e9tuation, \u00e0 notre \u00e9poque, des mitsvot qui s\u2019y accomplissaient, nous soignons la plaie de la destruction et de l\u2019exil, et h\u00e2tons la d\u00e9livrance (<em>Souka<\/em> 41a).<\/p>\n<p>On prend un c\u00e9drat, une branche de palmier, trois branches de myrte et deux branches de saule. En cas de n\u00e9cessit\u00e9 pressante, on prendra une seule branche de myrte et une seule branche de saule, mais sans prononcer la b\u00e9n\u00e9diction (<em>Choul\u2019han \u2018Aroukh<\/em> 651, 1)<sup><a id=\"_te01ftnref4_1\" class=\"aup1\" href=\"#_te01ftn4_1\">[1]<\/a><\/sup>.<\/p>\n<p>Si les esp\u00e8ces dont on dispose sont tr\u00e8s petites, elles ne sont pas valides pour la mitsva. La mesure minimale est\u00a0: pour le c\u00e9drat, un volume \u00e9quivalent au moins \u00e0 celui d\u2019un \u0153uf\u00a0; pour la branche de palmier, une longueur d\u2019au moins quatre <em>t\u00e9fa\u2019him\u00a0<\/em>; pour le myrte et le saule, une longueur d\u2019au moins trois <em>t\u00e9fa\u2019him<\/em>. Il n\u2019y a pas de limite sup\u00e9rieure\u00a0: tant qu\u2019on peut les porter, les quatre esp\u00e8ces sont cach\u00e8res. Nous approfondirons ces notions aux paragraphes 7, 8, 9 et 12, ainsi que dans les notes 4 et 6.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div><a id=\"_te01ftn4_1\" href=\"#_te01ftnref4_1\">[1]<\/a>. Selon Rabbi Tarfon, on prend trois branches de myrte et deux branches de saule\u00a0; or Rav Yehouda enseigne au nom de Chemouel\u00a0: \u00ab\u00a0La halakha est conforme \u00e0 l\u2019opinion de Rabbi Tarfon\u00a0\u00bb (<em>Souka<\/em> 34b). Telle est aussi l\u2019opinion de la majorit\u00e9 des d\u00e9cisionnaires, parmi lesquels\u00a0le <em>Halakhot Guedolot<\/em>, Ma\u00efmonide et le Roch\u00a0; de m\u00eame, le <em>Choul\u2019han \u2018Aroukh<\/em> 651, 1 tranche en ce sens. D\u2019autres pensent que la halakha suit Rabbi Aqiba, selon qui il suffit d\u2019avoir une branche de myrte et une branche de saule. Telle est l\u2019opinion de Na\u2019hmanide et du Ritva\u00a0; et le Rama \u00e9crit que, en cas de n\u00e9cessit\u00e9 pressante, on s\u2019appuie sur ces d\u00e9cisionnaires. Quoique certains auteurs estiment que l\u2019on doit r\u00e9citer la b\u00e9n\u00e9diction m\u00eame en ce cas (cf. <em>Michna Beroura<\/em> 6), de nombreux autres pensent qu\u2019on ne la r\u00e9cite point\u00a0; or, en cas de doute portant sur une b\u00e9n\u00e9diction, on s\u2019abstient.&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est une mitsva que de prendre, pendant la f\u00eate de Soukot, quatre esp\u00e8ces v\u00e9g\u00e9tales\u00a0(arba\u2019a minim) : le c\u00e9drat, la branche de palmier, le myrte et le saule, ainsi qu\u2019il est dit\u00a0: \u00ab\u00a0Et vous prendrez, le premier jour, le fruit de l\u2019arbre de splendeur, des palmes de dattier, des rameaux de l\u2019arbre feuillu et des saules [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[215],"tags":[],"class_list":["post-4965","post","type-post","status-publish","format-standard","hentry","category-13-04"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>01.La mitsva des quatre esp\u00e8ces - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"01.La mitsva des quatre esp\u00e8ces - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"C\u2019est une mitsva que de prendre, pendant la f\u00eate de Soukot, quatre esp\u00e8ces v\u00e9g\u00e9tales\u00a0(arba\u2019a minim) : le c\u00e9drat, la branche de palmier, le myrte et le saule, ainsi qu\u2019il est dit\u00a0: \u00ab\u00a0Et vous prendrez, le premier jour, le fruit de l\u2019arbre de splendeur, des palmes de dattier, des rameaux de l\u2019arbre feuillu et des saules [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2001-01-03T22:01:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-22T18:04:04+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-04-01\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-04-01\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"01.La mitsva des quatre esp\u00e8ces\",\"datePublished\":\"2001-01-03T22:01:02+00:00\",\"dateModified\":\"2021-08-22T18:04:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-04-01\\\/\"},\"wordCount\":748,\"articleSection\":[\"Chapitre 4 - Les quatre esp\u00e8ces (arba\u2019a minim)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-04-01\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-04-01\\\/\",\"name\":\"01.La mitsva des quatre esp\u00e8ces - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2001-01-03T22:01:02+00:00\",\"dateModified\":\"2021-08-22T18:04:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-04-01\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-04-01\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/13-04-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"01.La mitsva des quatre esp\u00e8ces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"01.La mitsva des quatre esp\u00e8ces - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/","og_locale":"fr_FR","og_type":"article","og_title":"01.La mitsva des quatre esp\u00e8ces - Pnin\u00e9 Halakha","og_description":"C\u2019est une mitsva que de prendre, pendant la f\u00eate de Soukot, quatre esp\u00e8ces v\u00e9g\u00e9tales\u00a0(arba\u2019a minim) : le c\u00e9drat, la branche de palmier, le myrte et le saule, ainsi qu\u2019il est dit\u00a0: \u00ab\u00a0Et vous prendrez, le premier jour, le fruit de l\u2019arbre de splendeur, des palmes de dattier, des rameaux de l\u2019arbre feuillu et des saules [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2001-01-03T22:01:02+00:00","article_modified_time":"2021-08-22T18:04:04+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"01.La mitsva des quatre esp\u00e8ces","datePublished":"2001-01-03T22:01:02+00:00","dateModified":"2021-08-22T18:04:04+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/"},"wordCount":748,"articleSection":["Chapitre 4 - Les quatre esp\u00e8ces (arba\u2019a minim)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/","url":"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/","name":"01.La mitsva des quatre esp\u00e8ces - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2001-01-03T22:01:02+00:00","dateModified":"2021-08-22T18:04:04+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/13-04-01\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/13-04-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"01.La mitsva des quatre esp\u00e8ces"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=4965"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/4965\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=4965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=4965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=4965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}