{"id":5358,"date":"2026-01-02T13:00:27","date_gmt":"2026-01-02T11:00:27","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=5358"},"modified":"2026-01-28T14:27:11","modified_gmt":"2026-01-28T12:27:11","slug":"10-02-13","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/","title":{"rendered":"13. Moment de la b\u00e9n\u00e9diction"},"content":{"rendered":"<p>On dit la b\u00e9n\u00e9diction <em>\u2018Al n\u00e9tilat yada\u00efm<\/em> apr\u00e8s s\u2019\u00eatre lav\u00e9 les mains, mais avant de les s\u00e9cher. De prime abord, il y a lieu de s\u2019interroger\u00a0: pour toute mitsva, nous disons la b\u00e9n\u00e9diction avant\u00a0de l\u2019accomplir, afin de sp\u00e9cifier notre intention \u00e0 l\u2019approche de cette mitsva. Pourquoi donc, dans le cas de cette b\u00e9n\u00e9diction, la pronon\u00e7ons-nous apr\u00e8s avoir accompli la mitsva, c\u2019est-\u00e0-dire apr\u00e8s l\u2019ablution\u00a0?<\/p>\n<p>La raison en est que, parfois, il n\u2019est pas possible de dire la b\u00e9n\u00e9diction avant l\u2019ablution, parce que les mains sont souill\u00e9es, or il ne convient pas de prononcer une b\u00e9n\u00e9diction avec des mains souill\u00e9es\u00a0; aussi la r\u00e9cite-t-on apr\u00e8s l\u2019ablution. Et pour ne pas cr\u00e9er de confusion dans l\u2019esprit de ceux qui se lavent les mains, l\u2019usage de r\u00e9citer la b\u00e9n\u00e9diction apr\u00e8s l\u2019ablution a \u00e9t\u00e9 fix\u00e9 \u00e9galement pour tout le monde. De m\u00eame, nous voyons qu\u2019un pros\u00e9lyte qui s\u2019immerge au bain rituel \u00e0 l\u2019occasion de sa conversion r\u00e9cite la b\u00e9n\u00e9diction sur l\u2019immersion apr\u00e8s s\u2019\u00eatre immerg\u00e9, car, avant l\u2019immersion, il est encore non juif, et ne peut donc pas prononcer de b\u00e9n\u00e9diction sur la conversion (cf. <em>Tossephot<\/em> sur <em>Berakhot<\/em> 51a, <em>Tour <\/em>et <em>Beit Yossef<\/em> 158, 11).<\/p>\n<p>De plus, s\u00e9cher ses mains fait partie de la mitsva, car il serait repoussant de manger du pain avec des mains humides\u00a0; or tout le propos de l\u2019ablution est de purifier et de nettoyer les mains en l\u2019honneur du repas (Rachi sur <em>Sota<\/em> 4b, <em>Michna Beroura<\/em> 158, 45-46). D\u2019apr\u00e8s cela, tant que l\u2019on dit la b\u00e9n\u00e9diction avant de se s\u00e9cher les mains, on consid\u00e8re encore qu\u2019elle est r\u00e9cit\u00e9e avant l\u2019ach\u00e8vement de la mitsva&lt;<sup><a id=\"_te01ftnref2_8\" class=\"aup1\" href=\"#_te01ftn2_8\">[8]<\/a><\/sup>.<\/p>\n<p>Puisque la b\u00e9n\u00e9diction se rapporte \u00e0 tout le processus d\u2019ablution, il est interdit de s\u2019interrompre par des paroles, pendant tout le temps qui s\u2019\u00e9tend de l\u2019ablution \u00e0 la fin du s\u00e9chage. Il faut se presser de dire la b\u00e9n\u00e9diction imm\u00e9diatement apr\u00e8s l\u2019ablution\u00a0; de m\u00eame, il faut se h\u00e2ter de se s\u00e9cher les mains d\u00e8s apr\u00e8s la fin de la b\u00e9n\u00e9diction.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div><a id=\"_te01ftn2_8\" href=\"#_te01ftnref2_8\">[8]<\/a>. Selon le <em>Tour\u00e9 Zahav<\/em> 158, 12, si l\u2019on a d\u00e9j\u00e0 s\u00e9ch\u00e9 ses mains, on a perdu la possibilit\u00e9 de dire la b\u00e9n\u00e9diction, puisqu\u2019on a achev\u00e9 la mitsva. Mais d\u2019apr\u00e8s la majorit\u00e9 des d\u00e9cisionnaires, parmi lesquels le Rema 158, 11, le <em>Maguen Avraham<\/em> 16 et le <em>Michna Beroura <\/em>44, tant que l\u2019on n\u2019a pas commenc\u00e9 la b\u00e9n\u00e9diction sur le pain, on peut encore, a posteriori, prononcer celle de l\u2019ablution. En effet, puisque la b\u00e9n\u00e9diction de l\u2019ablution a, fondamentalement, d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9plac\u00e9e, on peut la r\u00e9citer apr\u00e8s la fin du s\u00e9chage m\u00eame. Si l\u2019on veut apporter \u00e0 sa pratique un suppl\u00e9ment de perfection, on suivra le conseil du <em>Peri M\u00e9gadim, Michbetsot Zahav<\/em> 158, 12\u00a0: on touchera de ses doigts quelque endroit ordinairement couvert de son corps\u00a0; de cette fa\u00e7on, on sera oblig\u00e9 de recommencer l\u2019ablution\u00a0; on la recommencera donc, en r\u00e9citant cette fois la b\u00e9n\u00e9diction. Selon le <em>Ben Ich \u2018Ha\u00ef, Chemini<\/em> 7, ce n\u2019est que de cette fa\u00e7on que l\u2019on pourra la r\u00e9citer.Selon Ma\u00efmonide, <em>Berakhot<\/em> 6, 2, on dit la b\u00e9n\u00e9diction avant l\u2019ablution. Il est juste que ceux qui se conforment \u00e0 cette coutume [ce qui est le cas de certaines communaut\u00e9s y\u00e9m\u00e9nites] poursuivent dans cette voie. Toutefois, m\u00eame au Y\u00e9men, nombreux sont ceux qui ne partagent pas cette coutume (<em>Pisq\u00e9 Maharits, lois de la conduite de l\u2019homme le matin<\/em> 22).<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>On dit la b\u00e9n\u00e9diction \u2018Al n\u00e9tilat yada\u00efm apr\u00e8s s\u2019\u00eatre lav\u00e9 les mains, mais avant de les s\u00e9cher. De prime abord, il y a lieu de s\u2019interroger\u00a0: pour toute mitsva, nous disons la b\u00e9n\u00e9diction avant\u00a0de l\u2019accomplir, afin de sp\u00e9cifier notre intention \u00e0 l\u2019approche de cette mitsva. Pourquoi donc, dans le cas de cette b\u00e9n\u00e9diction, la pronon\u00e7ons-nous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[233],"tags":[],"class_list":["post-5358","post","type-post","status-publish","format-standard","hentry","category-10-02"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>13. Moment de la b\u00e9n\u00e9diction - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13. Moment de la b\u00e9n\u00e9diction - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"On dit la b\u00e9n\u00e9diction \u2018Al n\u00e9tilat yada\u00efm apr\u00e8s s\u2019\u00eatre lav\u00e9 les mains, mais avant de les s\u00e9cher. De prime abord, il y a lieu de s\u2019interroger\u00a0: pour toute mitsva, nous disons la b\u00e9n\u00e9diction avant\u00a0de l\u2019accomplir, afin de sp\u00e9cifier notre intention \u00e0 l\u2019approche de cette mitsva. Pourquoi donc, dans le cas de cette b\u00e9n\u00e9diction, la pronon\u00e7ons-nous [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-02T11:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T12:27:11+00:00\" \/>\n<meta name=\"author\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-02-13\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-02-13\\\/\"},\"author\":{\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"headline\":\"13. Moment de la b\u00e9n\u00e9diction\",\"datePublished\":\"2026-01-02T11:00:27+00:00\",\"dateModified\":\"2026-01-28T12:27:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-02-13\\\/\"},\"wordCount\":663,\"articleSection\":[\"Chapitre 02- Ablution des mains avant le repas\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-02-13\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-02-13\\\/\",\"name\":\"13. Moment de la b\u00e9n\u00e9diction - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2026-01-02T11:00:27+00:00\",\"dateModified\":\"2026-01-28T12:27:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-02-13\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-02-13\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-02-13\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"13. Moment de la b\u00e9n\u00e9diction\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\",\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"caption\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/thfvhacvcss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13. Moment de la b\u00e9n\u00e9diction - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/","og_locale":"fr_FR","og_type":"article","og_title":"13. Moment de la b\u00e9n\u00e9diction - Pnin\u00e9 Halakha","og_description":"On dit la b\u00e9n\u00e9diction \u2018Al n\u00e9tilat yada\u00efm apr\u00e8s s\u2019\u00eatre lav\u00e9 les mains, mais avant de les s\u00e9cher. De prime abord, il y a lieu de s\u2019interroger\u00a0: pour toute mitsva, nous disons la b\u00e9n\u00e9diction avant\u00a0de l\u2019accomplir, afin de sp\u00e9cifier notre intention \u00e0 l\u2019approche de cette mitsva. Pourquoi donc, dans le cas de cette b\u00e9n\u00e9diction, la pronon\u00e7ons-nous [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2026-01-02T11:00:27+00:00","article_modified_time":"2026-01-28T12:27:11+00:00","author":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/"},"author":{"name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"headline":"13. Moment de la b\u00e9n\u00e9diction","datePublished":"2026-01-02T11:00:27+00:00","dateModified":"2026-01-28T12:27:11+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/"},"wordCount":663,"articleSection":["Chapitre 02- Ablution des mains avant le repas"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/","url":"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/","name":"13. Moment de la b\u00e9n\u00e9diction - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2026-01-02T11:00:27+00:00","dateModified":"2026-01-28T12:27:11+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/10-02-13\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/10-02-13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"13. Moment de la b\u00e9n\u00e9diction"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178","name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","caption":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/thfvhacvcss\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/5358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=5358"}],"version-history":[{"count":3,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/5358\/revisions"}],"predecessor-version":[{"id":5715,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/5358\/revisions\/5715"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=5358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=5358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=5358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}