{"id":5647,"date":"2026-01-08T10:00:27","date_gmt":"2026-01-08T08:00:27","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=5647"},"modified":"2026-01-27T15:12:38","modified_gmt":"2026-01-27T13:12:38","slug":"10-08-10","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/","title":{"rendered":"10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s"},"content":{"rendered":"<p>Pour de la pur\u00e9e de fruits broy\u00e9s \u00e0 la machine (et dont on a l\u2019habitude de nourrir les b\u00e9b\u00e9s), la b\u00e9n\u00e9diction est <em>Ch\u00e9hakol<\/em>\u00a0: puisque ces fruits ont subi un complet broyage qui a modifi\u00e9 leur apparence, leur b\u00e9n\u00e9diction a chang\u00e9. Mais s\u2019il reste des morceaux de fruit \u00e0 l\u2019int\u00e9rieur de la pur\u00e9e, c\u2019est que les fruits n\u2019ont pas \u00e9t\u00e9 broy\u00e9s enti\u00e8rement\u00a0; on dira donc <em>Ha\u2018ets<\/em> sur les morceaux de fruit, ce par quoi on couvrira toute la pur\u00e9e (<em>Ben Ich \u2018Ha\u00ef, Pin\u2018has<\/em> 12).<\/p>\n<p>Pour une confiture ordinaire, sans morceaux de fruits, on dit <em>Ch\u00e9hakol<\/em>, quoique l\u2019on sache qu\u2019elle est faite de fruits. S\u2019il y reste des morceaux de fruits, on dira <em>Ha\u2018ets<\/em> sur les morceaux, ce par quoi l\u2019on exemptera le reste.<\/p>\n<p>Pour du concentr\u00e9 de tomates, la b\u00e9n\u00e9diction est <em>Ch\u00e9hakol<\/em>, puisque les tomates ont \u00e9t\u00e9 enti\u00e8rement broy\u00e9es. Certes, de nos jours, de tr\u00e8s nombreuses tomates sont cultiv\u00e9es pour la production de concentr\u00e9. Mais puisque l\u2019utilit\u00e9 essentielle du concentr\u00e9 de tomates est de donner du go\u00fbt aux plats, il n\u2019a pas d\u2019importance propre\u00a0; et puisque la tomate a enti\u00e8rement chang\u00e9 d\u2019apparence, celui qui mange de ce concentr\u00e9 dira <em>Ch\u00e9hakol<\/em>.<\/p>\n<p>Pour des snacks de ma\u00efs au beurre de cacahu\u00e8te (du type Bamba), on dit <em>Ch\u00e9hakol<\/em>. Bien que cela soit fait de farine de ma\u00efs et de beurre de cacahu\u00e8te, la b\u00e9n\u00e9diction est <em>Ch\u00e9hakol<\/em>, parce que ces v\u00e9g\u00e9taux sont enti\u00e8rement broy\u00e9s. De m\u00eame, on dit <em>Ch\u00e9hakol<\/em> sur le massepain (<em>marzipan<\/em>) fait d\u2019amandes moulues.<\/p>\n<p>Sur du <em>halva <\/em>(p\u00e2te de s\u00e9same sucr\u00e9e) ou de la <em>te\u2018hina<\/em> (ou <em>tahini<\/em>, cr\u00e8me de s\u00e9same), on dit <em>Ch\u00e9hakol\u00a0<\/em>: puisque les grains de s\u00e9same sont enti\u00e8rement moulus, qu\u2019ils ont perdu leur forme premi\u00e8re et qu\u2019on ne d\u00e9signerait pas ces pr\u00e9parations sous le nom de s\u00e9same, la b\u00e9n\u00e9diction est modifi\u00e9e<sup><a id=\"_te01ftnref8_7\" class=\"aup1\" href=\"#_te01ftn8_7\">[7]<\/a><\/sup>.<\/p>\n<p>Mais pour une friandise faite de grains de s\u00e9same, de sucre et de miel, on dira <em>Ha-adama<\/em>, puisque la majorit\u00e9 est constitu\u00e9e de grains de s\u00e9same qui n\u2019ont pas \u00e9t\u00e9 broy\u00e9s, et dont l\u2019aspect n\u2019a pas chang\u00e9.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div><a id=\"_te01ftn8_7\" href=\"#_te01ftnref8_7\">[7]<\/a>. Quand le fruit [ou le l\u00e9gume, ou le v\u00e9g\u00e9tal] est moulu, et que l\u2019on en a fait ensuite un autre aliment \u2013 \u00e0 l\u2019instar du millet et du ma\u00efs moulus que l\u2019on cuit au four pour en faire du pain \u2013, le <em>Choul\u2018han \u2018Aroukh<\/em> (208, 8) lui-m\u00eame, qui tranche selon l\u2019avis de Ma\u00efmonide, admet que l\u2019on dit <em>Ch\u00e9hakol<\/em>. La r\u00e8gle est la m\u00eame s\u2019agissant des Bamba et du <em>halva<\/em>, dont les ingr\u00e9dients ont d\u2019abord \u00e9t\u00e9 moulus, puis reconstitu\u00e9s tels un aliment nouveau.&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pour de la pur\u00e9e de fruits broy\u00e9s \u00e0 la machine (et dont on a l\u2019habitude de nourrir les b\u00e9b\u00e9s), la b\u00e9n\u00e9diction est Ch\u00e9hakol\u00a0: puisque ces fruits ont subi un complet broyage qui a modifi\u00e9 leur apparence, leur b\u00e9n\u00e9diction a chang\u00e9. Mais s\u2019il reste des morceaux de fruit \u00e0 l\u2019int\u00e9rieur de la pur\u00e9e, c\u2019est que les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[240],"tags":[],"class_list":["post-5647","post","type-post","status-publish","format-standard","hentry","category-chapitre-08-benedictions-des-fruits-et-des-legumes-chehakol"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Pour de la pur\u00e9e de fruits broy\u00e9s \u00e0 la machine (et dont on a l\u2019habitude de nourrir les b\u00e9b\u00e9s), la b\u00e9n\u00e9diction est Ch\u00e9hakol\u00a0: puisque ces fruits ont subi un complet broyage qui a modifi\u00e9 leur apparence, leur b\u00e9n\u00e9diction a chang\u00e9. Mais s\u2019il reste des morceaux de fruit \u00e0 l\u2019int\u00e9rieur de la pur\u00e9e, c\u2019est que les [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-08T08:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T13:12:38+00:00\" \/>\n<meta name=\"author\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-08-10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-08-10\\\/\"},\"author\":{\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"headline\":\"10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s\",\"datePublished\":\"2026-01-08T08:00:27+00:00\",\"dateModified\":\"2026-01-27T13:12:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-08-10\\\/\"},\"wordCount\":510,\"articleSection\":[\"Chapitre 08 - B\u00e9n\u00e9dictions des fruits et des l\u00e9gumes ; Ch\u00e9hakol\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-08-10\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-08-10\\\/\",\"name\":\"10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2026-01-08T08:00:27+00:00\",\"dateModified\":\"2026-01-27T13:12:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-08-10\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-08-10\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/10-08-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\",\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"caption\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/thfvhacvcss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/","og_locale":"fr_FR","og_type":"article","og_title":"10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s - Pnin\u00e9 Halakha","og_description":"Pour de la pur\u00e9e de fruits broy\u00e9s \u00e0 la machine (et dont on a l\u2019habitude de nourrir les b\u00e9b\u00e9s), la b\u00e9n\u00e9diction est Ch\u00e9hakol\u00a0: puisque ces fruits ont subi un complet broyage qui a modifi\u00e9 leur apparence, leur b\u00e9n\u00e9diction a chang\u00e9. Mais s\u2019il reste des morceaux de fruit \u00e0 l\u2019int\u00e9rieur de la pur\u00e9e, c\u2019est que les [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2026-01-08T08:00:27+00:00","article_modified_time":"2026-01-27T13:12:38+00:00","author":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/"},"author":{"name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"headline":"10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s","datePublished":"2026-01-08T08:00:27+00:00","dateModified":"2026-01-27T13:12:38+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/"},"wordCount":510,"articleSection":["Chapitre 08 - B\u00e9n\u00e9dictions des fruits et des l\u00e9gumes ; Ch\u00e9hakol"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/","url":"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/","name":"10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2026-01-08T08:00:27+00:00","dateModified":"2026-01-27T13:12:38+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/10-08-10\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/10-08-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"10. Fruits et l\u00e9gumes enti\u00e8rement broy\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178","name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","caption":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/thfvhacvcss\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/5647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=5647"}],"version-history":[{"count":2,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/5647\/revisions"}],"predecessor-version":[{"id":5649,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/5647\/revisions\/5649"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=5647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=5647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=5647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}