{"id":97,"date":"2016-01-14T05:00:43","date_gmt":"2016-01-14T03:00:43","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=97"},"modified":"2018-03-19T10:54:12","modified_gmt":"2018-03-19T08:54:12","slug":"05-14-05","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/","title":{"rendered":"05. La mitsva d\u2019effacer Amaleq"},"content":{"rendered":"<p>La mitsva d\u2019effacer le souvenir d\u2019Amaleq incombe essentiellement \u00e0 la <em>collectivit\u00e9 <\/em>d\u2019Isra\u00ebl. Nos sages disent ainsi que trois mitsvot furent prescrites au peuple h\u00e9breu quand il entra sur la terre d\u2019Isra\u00ebl\u00a0: d\u2019abord, se d\u00e9signer un roi\u00a0; puis retrancher la descendance d\u2019Amaleq\u00a0; enfin, construire la Maison d\u2019\u00e9lection (le Temple) (<em>Sanh\u00e9drin<\/em> 20b).<\/p>\n<p>Et en effet\u00a0: apr\u00e8s qu\u2019Isra\u00ebl se fut consolid\u00e9 sur sa terre, que les H\u00e9breux eurent d\u00e9sign\u00e9 Sa\u00fcl comme roi, et que son r\u00e8gne se fut affermi, le proph\u00e8te Samuel vint voir Sa\u00fcl et lui dit\u00a0: \u00ab\u00a0L\u2019Eternel m\u2019avait envoy\u00e9 pour te sacrer roi de son peuple Isra\u00ebl. Et maintenant, \u00e9coute les paroles de l\u2019Eternel. Ainsi a dit l\u2019Eternel, Dieu des Arm\u00e9es\u00a0: \u201cJe convoque le souvenir de ce qu\u2019Amaleq a fait \u00e0 Isra\u00ebl\u00a0: il combattit contre lui en chemin, quand il monta de l\u2019Egypte. Maintenant, va et frappe Amaleq, et tu frapperas d\u2019anath\u00e8me tout ce qui est \u00e0 lui\u00a0; tu ne le prendras pas en piti\u00e9, et tu mettras \u00e0 mort homme et femme, enfant et nourrisson, b\u0153uf et agneau, chameau et \u00e2ne\u201d\u00a0\u00bb (Sam 15, 1-3).<\/p>\n<p>Mais le roi Sa\u00fcl n\u2019accomplit pas la mitsva comme elle s\u2019imposait\u00a0: il eut piti\u00e9 d\u2019Agag, roi d\u2019Amaleq, et de la meilleure partie du petit et du gros b\u00e9tail. C\u2019est \u00e0 la suite de cet \u00e9pisode que l\u2019Eternel lui retira la royaut\u00e9 et la donna \u00e0 David. Cependant, le dommage \u00e9tait d\u00e9j\u00e0 tr\u00e8s grand. Du fait de la faiblesse que constitua la mis\u00e9ricorde excessive de Sa\u00fcl, de nombreux Amal\u00e9cites rest\u00e8rent en vie, qui continu\u00e8rent de tourmenter Isra\u00ebl. Quelques ann\u00e9es apr\u00e8s, un bataillon amal\u00e9cite s\u2019abattit sur Ciklag, la ville o\u00f9 vivaient la famille de David et celles de ses compagnons d\u2019arme\u00a0; ce bataillon br\u00fbla la ville et captura toutes les femmes et les enfants. Par la gr\u00e2ce de Dieu, David et ses gens r\u00e9ussirent \u00e0 sauver les captifs et \u00e0 frapper ce bataillon. Mais comme David n\u2019\u00e9tait pas encore roi, et que l\u2019arm\u00e9e d\u2019Isra\u00ebl n\u2019\u00e9tait pas \u00e0 sa disposition, il ne r\u00e9ussit pas \u00e0 les d\u00e9truire, et il resta quatre cents jeunes hommes de ce bataillon, qui montaient des chameaux, et qui s\u2019enfuirent (I Sam 30). Il resta vraisemblablement d\u2019autres groupes d\u2019Amal\u00e9cites en d\u2019autres endroits. Apr\u00e8s que David fut devenu roi, et bien qu\u2019il les combatt\u00eet, il n\u2019\u00e9tait plus possible de les combattre tous et de les d\u00e9truire, en raison de leur dispersion. Nos sages racontent encore que c\u2019est en raison de ce fait m\u00eame \u2013 l\u2019ajournement de l\u2019ex\u00e9cution d\u2019Agag par Sa\u00fcl \u2013 que la descendance\u00a0du roi amal\u00e9cite put venir au monde ; et c\u2019est \u00e0 partir d\u2019elle que naquit ensuite Haman l\u2019Agaguite, qui voulut exterminer, d\u00e9truire et an\u00e9antir tout Isra\u00ebl (<em>M\u00e9guila<\/em> 13a).<\/p>\n<p>Bien que la mitsva d\u2019effacer Amaleq incombe essentiellement \u00e0 la collectivit\u00e9, elle incombe \u00e9galement \u00e0 chaque membre du peuple juif\u00a0: si l\u2019on se trouve en pr\u00e9sence d\u2019un Amal\u00e9cite, que l\u2019on ait la force de le tuer, et que l\u2019on s\u2019en abstienne, on contrevient par-l\u00e0 \u00e0 cette mitsva (<em>S\u00e9fer Ha\u2019hinoukh<\/em> 604). De nos jours, la descendance d\u2019Amaleq est perdue\u00a0; toutefois, s\u2019il apparaissait que telle personne est amal\u00e9cite et suit les voies de ses anc\u00eatres, ce serait une mitsva que de l\u2019ex\u00e9cuter<sup><a href='#_te01ftn14_5' id='_te01ftnref14_5' class='aup1'>[5]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref14_5' id='_te01ftn14_5'>[5]<\/a>. Les responsa <em>Qol Mevasser<\/em> 2, 42 d\u00e9duisent des propos de Ma\u00efmonide, de Na\u2019hmanide (Ex 17, 16) et du <em>S\u00e9fer Ha\u2019hinoukh<\/em> 604 que la mitsva d\u2019effacer le souvenir d\u2019Amaleq (<em>me\u2019hiat Amaleq<\/em>) repose essentiellement sur le roi et sur la collectivit\u00e9, mais que l\u2019individu lui aussi, s\u2019il le peut, a l\u2019obligation d\u2019ex\u00e9cuter l\u2019Amal\u00e9cite.<\/p>\n<p>Quant \u00e0 ce que nous \u00e9crivons sur les Amal\u00e9cites qui subsist\u00e8rent apr\u00e8s les combats men\u00e9s par David, c\u2019est ce qui ressort de la Gu\u00e9mara <em>Baba Batra<\/em> 21a, o\u00f9 il est dit que Joab, ministre de la guerre de David, se trompa en raison de la confusion de son ma\u00eetre, et ne tua que les hommes, et non les femmes. C\u2019\u00e9tait lors de la guerre racont\u00e9e en I Rois 11, 15-16. Bien que le front principal de la guerre f\u00fbt alors l\u2019Idum\u00e9e, c\u2019est-\u00e0-dire les descendants d\u2019Esa\u00fc, et qu\u2019Amaleq ne constitu\u00e2t qu\u2019une petite partie de cette descendance, le texte laisse entendre que des groupes d\u2019Amal\u00e9cites se trouvaient l\u00e0, et que c\u2019est \u00e0 leur sujet que Joab fit erreur. C\u2019est ce qu\u2019explique le <em>Qol Mevasser<\/em> 2, 42.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La mitsva d\u2019effacer le souvenir d\u2019Amaleq incombe essentiellement \u00e0 la collectivit\u00e9 d\u2019Isra\u00ebl. Nos sages disent ainsi que trois mitsvot furent prescrites au peuple h\u00e9breu quand il entra sur la terre d\u2019Isra\u00ebl\u00a0: d\u2019abord, se d\u00e9signer un roi\u00a0; puis retrancher la descendance d\u2019Amaleq\u00a0; enfin, construire la Maison d\u2019\u00e9lection (le Temple) (Sanh\u00e9drin 20b). Et en effet\u00a0: apr\u00e8s qu\u2019Isra\u00ebl [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-97","post","type-post","status-publish","format-standard","hentry","category-05-14"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>05. La mitsva d\u2019effacer Amaleq - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"05. La mitsva d\u2019effacer Amaleq - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"La mitsva d\u2019effacer le souvenir d\u2019Amaleq incombe essentiellement \u00e0 la collectivit\u00e9 d\u2019Isra\u00ebl. Nos sages disent ainsi que trois mitsvot furent prescrites au peuple h\u00e9breu quand il entra sur la terre d\u2019Isra\u00ebl\u00a0: d\u2019abord, se d\u00e9signer un roi\u00a0; puis retrancher la descendance d\u2019Amaleq\u00a0; enfin, construire la Maison d\u2019\u00e9lection (le Temple) (Sanh\u00e9drin 20b). Et en effet\u00a0: apr\u00e8s qu\u2019Isra\u00ebl [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-14T03:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-19T08:54:12+00:00\" \/>\n<meta name=\"author\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-14-05\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-14-05\\\/\"},\"author\":{\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"headline\":\"05. La mitsva d\u2019effacer Amaleq\",\"datePublished\":\"2016-01-14T03:00:43+00:00\",\"dateModified\":\"2018-03-19T08:54:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-14-05\\\/\"},\"wordCount\":810,\"articleSection\":[\"Chapitre 14 - Le mois d\u2019adar\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-14-05\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-14-05\\\/\",\"name\":\"05. La mitsva d\u2019effacer Amaleq - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-01-14T03:00:43+00:00\",\"dateModified\":\"2018-03-19T08:54:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-14-05\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-14-05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-14-05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"05. La mitsva d\u2019effacer Amaleq\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\",\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"caption\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/thfvhacvcss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"05. La mitsva d\u2019effacer Amaleq - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/","og_locale":"fr_FR","og_type":"article","og_title":"05. La mitsva d\u2019effacer Amaleq - Pnin\u00e9 Halakha","og_description":"La mitsva d\u2019effacer le souvenir d\u2019Amaleq incombe essentiellement \u00e0 la collectivit\u00e9 d\u2019Isra\u00ebl. Nos sages disent ainsi que trois mitsvot furent prescrites au peuple h\u00e9breu quand il entra sur la terre d\u2019Isra\u00ebl\u00a0: d\u2019abord, se d\u00e9signer un roi\u00a0; puis retrancher la descendance d\u2019Amaleq\u00a0; enfin, construire la Maison d\u2019\u00e9lection (le Temple) (Sanh\u00e9drin 20b). Et en effet\u00a0: apr\u00e8s qu\u2019Isra\u00ebl [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-01-14T03:00:43+00:00","article_modified_time":"2018-03-19T08:54:12+00:00","author":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/"},"author":{"name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"headline":"05. La mitsva d\u2019effacer Amaleq","datePublished":"2016-01-14T03:00:43+00:00","dateModified":"2018-03-19T08:54:12+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/"},"wordCount":810,"articleSection":["Chapitre 14 - Le mois d\u2019adar"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/","url":"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/","name":"05. La mitsva d\u2019effacer Amaleq - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-01-14T03:00:43+00:00","dateModified":"2018-03-19T08:54:12+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/05-14-05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/05-14-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"05. La mitsva d\u2019effacer Amaleq"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178","name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","caption":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/thfvhacvcss\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=97"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/97\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=97"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=97"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}